{"id":14593,"date":"2023-12-11T14:19:30","date_gmt":"2023-12-11T19:19:30","guid":{"rendered":"https:\/\/www.hoosierenergy.com\/?p=14593"},"modified":"2023-12-11T14:19:30","modified_gmt":"2023-12-11T19:19:30","slug":"tommy-roberts-qa-riding-technologys-roller-coaster","status":"publish","type":"post","link":"https:\/\/www.hoosierenergy.com\/pt\/news-resources\/tommy-roberts-qa-riding-technologys-roller-coaster\/","title":{"rendered":"Tommy Roberts Q&amp;A: Andando na montanha-russa da tecnologia"},"content":{"rendered":"<p>A foto da capa de sua p\u00e1gina do Facebook \u00e9 o Coney Island Cyclone. E isso por si s\u00f3 pode sugerir que Tommy Roberts \u00e9 capaz de surfar nos altos e baixos da ind\u00fastria de servi\u00e7os p\u00fablicos.<\/p>\n<p>&nbsp;<\/p>\n<p>O gerente de servi\u00e7os de engenharia da Hoosier Energy n\u00e3o \u00e9 apenas um aficionado por montanhas-russas, mas tamb\u00e9m est\u00e1 ajudando a orientar a integra\u00e7\u00e3o de tecnologia nos servi\u00e7os de transmiss\u00e3o da Hoosier.<\/p>\n<p>&nbsp;<\/p>\n<p>Roberts, que est\u00e1 na empresa h\u00e1 mais de 15 anos, sentou-se recentemente para conversar sobre essas duas coisas com a GridLines.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: A tecnologia est\u00e1 sempre avan\u00e7ando e mudando. Como voc\u00ea supervisiona o que a Hoosier usa?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Uma das nossas tarefas \u00e9 ficar a par das tecnologias emergentes, especialmente quando se trata de tecnologias de transmiss\u00e3o e subesta\u00e7\u00e3o. A maneira como fazemos isso \u00e9 alavancar nossa associa\u00e7\u00e3o e parceria com institui\u00e7\u00f5es que fazem muitas dessas pesquisas e podem ajudar a ser um multiplicador de for\u00e7a, j\u00e1 que temos um n\u00famero limitado de recursos e n\u00e3o podemos estar em tudo. Essas organiza\u00e7\u00f5es nos ajudam a olhar, priorizar e resumir essas tecnologias emergentes. Geralmente \u00e9 o EPRI (Electric Power Research Institute) e o NATF (North American Transmission Forum).<\/p>\n<p>&nbsp;<\/p>\n<p>Basicamente, usamos essas organiza\u00e7\u00f5es e vamos a confer\u00eancias ou participamos de webinars e nos envolvemos em grupos de interesse para termos a oportunidade de aprender e obter exposi\u00e7\u00e3o a novas tecnologias em diferentes esferas, seja em linhas de transmiss\u00e3o, tecnologias de aprimoramento de rede, tecnologias de subesta\u00e7\u00f5es, novas tecnologias operacionais ou drones, que s\u00e3o um grande t\u00f3pico de conversa.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: Como a Hoosier Energy decide quais tecnologias atendem aos nossos interesses?<\/strong><\/p>\n<p>Nosso maior retorno sobre o investimento \u00e9 deixar que a EPRI ou a NATF experimentem diferentes tecnologias e nos deem um resumo desses aprendizados. Tudo o que fazemos do ponto de vista t\u00e9cnico \u00e9 limitado. Tentamos ser conservadores no que estamos usando e colocando l\u00e1 fora. \u00c9 preciso muito para entrar em nosso prato em servi\u00e7os de engenharia.<\/p>\n<p>&nbsp;<\/p>\n<p>Confiabilidade \u00e9 a coisa mais importante e estamos focados nisso, ent\u00e3o n\u00e3o temos tempo para nos dedicar a testar novas tecnologias. Precisamos que outros as testem e nos deem um relat\u00f3rio e podemos come\u00e7ar a aprender sobre isso. Precisa estar em um certo n\u00edvel de desenvolvimento antes de poder ser usado na Hoosier.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: Quais s\u00e3o algumas das novidades mais recentes do ponto de vista tecnol\u00f3gico?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_7376\" style=\"width: 305px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-7376\" class=\"wp-image-7376\" src=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2021\/09\/Tommy-Roberts-300x178.jpg\" alt=\"\" width=\"295\" height=\"175\" srcset=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2021\/09\/Tommy-Roberts-300x178.jpg 300w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2021\/09\/Tommy-Roberts-768x455.jpg 768w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2021\/09\/Tommy-Roberts-18x12.jpg 18w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2021\/09\/Tommy-Roberts.jpg 796w\" sizes=\"auto, (max-width: 295px) 100vw, 295px\" \/><p id=\"caption-attachment-7376\" class=\"wp-caption-text\">Tommy Roberts<\/p><\/div>\n<p>Acho que muito do foco recente tem sido a coleta e o gerenciamento de dados e o compartilhamento de informa\u00e7\u00f5es entre sistemas e como isso se parece e qu\u00e3o integrados estamos? A Hoosier Energy continua a fazer progressos para pegar nosso sistema de gerenciamento de ativos corporativos e vincul\u00e1-lo ao GIS (Sistema de Informa\u00e7\u00e3o Geogr\u00e1fica) com muito do foco atual em integra\u00e7\u00f5es de dados e como podemos fazer um trabalho melhor com qualidade de dados e gerenciamento de dados para melhor alavancar tecnologias futuras.<\/p>\n<p>&nbsp;<\/p>\n<p>Quando voc\u00ea olha para as tecnologias na vanguarda, h\u00e1 coisas como realidade aumentada. Por exemplo, voc\u00ea pode pegar uma c\u00e2mera de celular e ela projetar\u00e1 a imagem do seu design na tela enquanto voc\u00ea olha para algo no campo. Ent\u00e3o voc\u00ea pode ter linhas de transmiss\u00e3o que voc\u00ea criou digitalmente e traz\u00ea-las para o campo e mostrar no seu telefone como algo se parece, quais s\u00e3o as folgas para \u00e1rvores, etc. \u00c9 tudo sobre trazer esse mundo digital para o mundo real.<\/p>\n<p>&nbsp;<\/p>\n<p>Estamos focados em estreitar essas integra\u00e7\u00f5es e os dados para que possamos chegar a esse mundo futuro onde esse modelo digital ou g\u00eameo digital exista. Ent\u00e3o, podemos come\u00e7ar a alavancar essas tecnologias futuras.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: Voc\u00ea mencionou o t\u00f3pico de drones. Onde fica o uso de drones na frente de transmiss\u00e3o?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Alguns eletricistas da Hoosier Energy agora s\u00e3o operadores de drones certificados, ent\u00e3o cabe a eles decidir quando \u00e9 apropriado levar um drone para inspe\u00e7\u00f5es para ajudar com coisas que est\u00e3o al\u00e9m da linha de vis\u00e3o no n\u00edvel do solo, como o topo dos postes.<\/p>\n<p>&nbsp;<\/p>\n<p>O uso desses drones s\u00f3 vai aumentar. H\u00e1 um futuro l\u00e1 fora onde os drones se tornar\u00e3o mais orientados para IA, onde n\u00e3o se trata de ter um piloto, mas sim da capacidade de ter um drone atracado em uma subesta\u00e7\u00e3o. Se algo acontecer no meio da noite, voc\u00ea pode pilotar essa coisa remotamente do centro de opera\u00e7\u00f5es no Condado de Owen ou autonomamente, ele inspecionar\u00e1 a subesta\u00e7\u00e3o antes que algu\u00e9m esteja no local, tornando-se o primeiro a responder.<\/p>\n<p>&nbsp;<\/p>\n<p>O drone est\u00e1 l\u00e1 fora, avaliando o que aconteceu e alimentando informa\u00e7\u00f5es para o controle do sistema e nossos socorristas, para que eles n\u00e3o entrem em uma situa\u00e7\u00e3o desconhecida. Quando chegarmos a esse ponto, ser\u00e1 uma grande vantagem do ponto de vista da confiabilidade, restaura\u00e7\u00e3o do sistema e seguran\u00e7a.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: Sempre h\u00e1 alguma preocupa\u00e7\u00e3o de que a tecnologia v\u00e1 substituir as pessoas. Esse n\u00e3o \u00e9 o objetivo, certo?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Em nosso neg\u00f3cio especialmente, acho que vai tornar os trabalhos mais seguros com drones capazes de voar uma linha e ajudar a identificar uma interrup\u00e7\u00e3o no meio de uma tempestade de neve ou no meio da noite. Isso \u00e9 feedback em tempo real em condi\u00e7\u00f5es perigosas quando normalmente ter\u00edamos eletricistas subindo e descendo a linha para ver o que est\u00e1 errado. N\u00e3o h\u00e1 uma vida na linha com o drone, e ent\u00e3o a informa\u00e7\u00e3o dir\u00e1 aos eletricistas para irem exatamente onde s\u00e3o necess\u00e1rios. Isso poderia potencialmente tornar a situa\u00e7\u00e3o muito mais segura para as pessoas no campo.<\/p>\n<p>&nbsp;<\/p>\n<p>Nunca haver\u00e1 um substituto para um lineman. Tudo o que os drones podem realmente fazer \u00e9 fornecer um aux\u00edlio visual extra. No que fazemos, ser\u00e1 um futuro realmente interessante, \u00e0 medida que essa tecnologia se desenvolve e a FAA aprova drones al\u00e9m da linha de vis\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: O que est\u00e1 por vir?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>H\u00e1 muita conversa sobre o que \u00e9 chamado de GETs, Grid Enhancing Technologies. Continua sendo algo que monitoramos, mas para Hoosier, a grande quest\u00e3o s\u00e3o as classifica\u00e7\u00f5es de linha din\u00e2micas, o que significa que, dependendo das condi\u00e7\u00f5es, a quantidade de energia que voc\u00ea pode transferir por uma linha de energia pode ser muito diferente.<\/p>\n<p>&nbsp;<\/p>\n<p>Voc\u00ea est\u00e1 preocupado com a temperatura do seu condutor, ent\u00e3o se estiver muito quente l\u00e1 fora com muito sol, potencialmente voc\u00ea move menos energia do que se estiver muito frio e ventoso e mantendo esses condutores frios. As classifica\u00e7\u00f5es din\u00e2micas de linha usam tecnologia, monitoramento de clima e condi\u00e7\u00f5es para um sistema que analisa os condutores e faz avalia\u00e7\u00f5es do ponto de vista da capacidade de calor. A inten\u00e7\u00e3o \u00e9 dizer se podemos colocar mais energia nesta linha at\u00e9 um certo ponto. As classifica\u00e7\u00f5es din\u00e2micas de linha s\u00e3o algo que recebe muita aten\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>H\u00e1 o uso de classifica\u00e7\u00f5es ajustadas de ambiente, que temos que fazer com o MISO em 2025, ent\u00e3o isso \u00e9 visto como um precursor das classifica\u00e7\u00f5es de linha din\u00e2mica. Ambiente significa que vamos olhar para a temperatura e ajustar para qual \u00e9 a temperatura externa, mas uma classifica\u00e7\u00e3o din\u00e2mica verdadeira \u00e9 o que eles est\u00e3o trabalhando. Existem programas piloto por a\u00ed, que continuamos monitorando, mas esse \u00e9 um dos GETs que podem chegar a Hoosier dependendo dos mandatos da FERC e do que eles querem ver.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: Voc\u00ea j\u00e1 imaginou acompanhar todas essas tecnologias quando estudava engenharia?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Eu me formei em engenharia mec\u00e2nica pela Rose-Hulman e passei os primeiros 11 ou 12 anos na Hoosier Energy trabalhando em gest\u00e3o de ativos de gera\u00e7\u00e3o, realizando grandes projetos de capital e estudos de engenharia no lado da gera\u00e7\u00e3o. Depois, entrei na gest\u00e3o de ativos de transmiss\u00e3o e agora sou gerente de servi\u00e7os de engenharia.<\/p>\n<p>&nbsp;<\/p>\n<p>Aprender sobre novas tecnologias sempre foi algo que me empolga e me mant\u00e9m ativo. Isso torna cada dia novo, \u00e0 medida que voc\u00ea aprende sobre algum outro aspecto da tecnologia emergente ou a maneira como outra coisa funciona. Tendo uma boa amplitude de tantas disciplinas de engenharia dentro do nosso grupo \u2013 engenheiros el\u00e9tricos, engenheiros civis, engenheiros mec\u00e2nicos, fazendo uso de comunica\u00e7\u00f5es \u2013 podemos falar sobre muitas tecnologias diferentes que tornam isso emocionante.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: O que despertou seu interesse em engenharia quando voc\u00ea era mais jovem?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Sempre fui um aficionado e entusiasta de montanhas-russas, e minha mat\u00e9ria favorita no ensino m\u00e9dio era f\u00edsica, ent\u00e3o, quando voc\u00ea junta essas coisas, descobre que engenharia \u00e9 onde voc\u00ea quer estar.<\/p>\n<p>&nbsp;<\/p>\n<p>Acontece que n\u00e3o h\u00e1 muitos empregos projetando montanhas-russas. H\u00e1 muita competi\u00e7\u00e3o para isso, e \u00e9 um mercado bem pequeno, mas muitas das coisas que eu gostava sobre esse hobby e como as coisas s\u00e3o t\u00e3o diferentes de parque para parque, com cada um tendo pequenas diferen\u00e7as, era meio que o mesmo em gera\u00e7\u00e3o se voc\u00ea olhar de um n\u00edvel macro. Cada usina de energia tem sua pr\u00f3pria mistura \u00fanica de tecnologias combinadas com idiossincrasias geogr\u00e1ficas que influenciam nisso - como elas obt\u00eam \u00e1gua, como elas colocam seu combust\u00edvel na esta\u00e7\u00e3o, que tipo de combust\u00edvel \u00e9, como isso impacta a tecnologia, controles de polui\u00e7\u00e3o, que tipo de caldeira?<\/p>\n<p>&nbsp;<\/p>\n<p>Uma coisa no lado do carv\u00e3o era o qu\u00e3o \u00fanica cada usina era, e isso me atraiu que cada usina era seu pr\u00f3prio problema que exigia uma solu\u00e7\u00e3o \u00fanica. Em Hoosier, Ratts e Merom eram completamente diferentes. Voc\u00ea n\u00e3o pode pegar uma resposta e resolver problemas em ambos os lugares. Elas eram \u00fanicas, e voc\u00ea tinha que saber a diferen\u00e7a. E comparando essas usinas com outras usinas em Indiana ou nos EUA, voc\u00ea tinha que entender outras diferen\u00e7as.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: De onde voc\u00ea \u00e9 e quais parques tem\u00e1ticos despertaram o interesse em montanhas-russas?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Eu sou de perto. Passei um bom tempo nos sub\u00farbios de Chicago e depois fui para o ensino m\u00e9dio em Connecticut. Eu queria voltar para o Centro-Oeste e acabei na Rose-Hulman para a escola de engenharia e estou em Indiana desde ent\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>Cedar Point sempre foi meu favorito, mas tamb\u00e9m gosto do Islands of Adventure, do Six Flags Magic Mountain na Calif\u00f3rnia, do Six Flags Great America em Chicago, do Six Flags Great Adventure em Nova Jersey e do Six Flags New England.<\/p>\n<p>&nbsp;<\/p>\n<p>J\u00e1 estive em quase todos os parques dos EUA, menos Utah, que \u00e9 o \u00fanico estado em que n\u00e3o estive em um parque de divers\u00f5es. Em nenhum parque grande que estive. J\u00e1 andei em mais de 440 montanhas-russas e j\u00e1 fui a alguns parques de divers\u00f5es na Europa \u2013 Fran\u00e7a e Reino Unido.<\/p>\n<p>&nbsp;<\/p>\n<p>N\u00e3o viajo assim agora. Quando voc\u00ea tem filhos, \u00e9 dif\u00edcil fazer isso.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: Quais s\u00e3o suas montanhas-russas favoritas?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Millenium Force no Cedar Point \u00e9 definitivamente o meu favorito. Super Man no Six Flags New England \u00e9 um favorito.<\/p>\n<p>&nbsp;<\/p>\n<p>Gosto de uma boa montanha-russa de madeira, ent\u00e3o adoro The Voyage no Holiday World. \u00c9 uma das poucas que, no final, estou pronto para terminar.<\/p>","protected":false},"excerpt":{"rendered":"A foto da capa de sua p\u00e1gina do Facebook \u00e9 o Coney Island Cyclone. E isso por si s\u00f3 pode sugerir que Tommy Roberts \u00e9 capaz de surfar os altos e baixos do"},"author":7,"featured_media":14594,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-14593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spotlight-stories","category-18","description-off"],"acf":false,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Tommy Roberts Q&amp;A: Riding technology&#039;s roller coaster - Hoosier Energy<\/title>\r\n<meta name=\"description\" content=\"Hoosier Energy&#039;s Tommy Roberts helps the cooperative navigate the ups and downs of technology in the utility industry.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.hoosierenergy.com\/pt\/news-resources\/tommy-roberts-qa-riding-technologys-roller-coaster\/\" \/>\r\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Tommy Roberts Q&amp;A: Riding technology&#039;s roller coaster - Hoosier Energy\" \/>\r\n<meta property=\"og:description\" content=\"Hoosier Energy&#039;s Tommy Roberts helps the cooperative navigate the ups and downs of technology in the utility industry.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.hoosierenergy.com\/pt\/news-resources\/tommy-roberts-qa-riding-technologys-roller-coaster\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Hoosier Energy\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HoosierEnergy\" \/>\r\n<meta property=\"article:published_time\" content=\"2023-12-11T19:19:30+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/12\/Coneycyclone2.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1778\" \/>\r\n\t<meta property=\"og:image:height\" content=\"712\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Jeremy Price\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@hoosierenergy\" \/>\r\n<meta name=\"twitter:site\" content=\"@hoosierenergy\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jeremy Price\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/tommy-roberts-qa-riding-technologys-roller-coaster\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/tommy-roberts-qa-riding-technologys-roller-coaster\\\/\"},\"author\":{\"name\":\"Jeremy Price\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\"},\"headline\":\"Tommy Roberts Q&#038;A: Riding technology&#8217;s roller coaster\",\"datePublished\":\"2023-12-11T19:19:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/tommy-roberts-qa-riding-technologys-roller-coaster\\\/\"},\"wordCount\":1856,\"image\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/tommy-roberts-qa-riding-technologys-roller-coaster\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Coneycyclone2.jpg\",\"articleSection\":[\"Spotlight Stories\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/tommy-roberts-qa-riding-technologys-roller-coaster\\\/\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/tommy-roberts-qa-riding-technologys-roller-coaster\\\/\",\"name\":\"Tommy Roberts Q&A: Riding technology's roller coaster - Hoosier Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/tommy-roberts-qa-riding-technologys-roller-coaster\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/tommy-roberts-qa-riding-technologys-roller-coaster\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Coneycyclone2.jpg\",\"datePublished\":\"2023-12-11T19:19:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\"},\"description\":\"Hoosier Energy's Tommy Roberts helps the cooperative navigate the ups and downs of technology in the utility industry.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/tommy-roberts-qa-riding-technologys-roller-coaster\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/tommy-roberts-qa-riding-technologys-roller-coaster\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/tommy-roberts-qa-riding-technologys-roller-coaster\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Coneycyclone2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Coneycyclone2.jpg\",\"width\":1778,\"height\":712},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/tommy-roberts-qa-riding-technologys-roller-coaster\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hoosierenergy.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tommy Roberts Q&#038;A: Riding technology&#8217;s roller coaster\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#website\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/\",\"name\":\"Hoosier Energy\",\"description\":\"Powering Community\",\"alternateName\":\"Hoosier Energy Rural Electric Cooperative, Inc.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hoosierenergy.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\",\"name\":\"Jeremy Price\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrevista com Tommy Roberts: A montanha-russa da tecnologia - Hoosier Energy","description":"Tommy Roberts, da Hoosier Energy, ajuda a cooperativa a lidar com os altos e baixos da tecnologia no setor de energia el\u00e9trica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hoosierenergy.com\/pt\/news-resources\/tommy-roberts-qa-riding-technologys-roller-coaster\/","og_locale":"pt_PT","og_type":"article","og_title":"Tommy Roberts Q&A: Riding technology's roller coaster - Hoosier Energy","og_description":"Hoosier Energy's Tommy Roberts helps the cooperative navigate the ups and downs of technology in the utility industry.","og_url":"https:\/\/www.hoosierenergy.com\/pt\/news-resources\/tommy-roberts-qa-riding-technologys-roller-coaster\/","og_site_name":"Hoosier Energy","article_publisher":"https:\/\/www.facebook.com\/HoosierEnergy","article_published_time":"2023-12-11T19:19:30+00:00","og_image":[{"width":1778,"height":712,"url":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/12\/Coneycyclone2.jpg","type":"image\/jpeg"}],"author":"Jeremy Price","twitter_card":"summary_large_image","twitter_creator":"@hoosierenergy","twitter_site":"@hoosierenergy","twitter_misc":{"Escrito por":"Jeremy Price","Tempo estimado de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/tommy-roberts-qa-riding-technologys-roller-coaster\/#article","isPartOf":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/tommy-roberts-qa-riding-technologys-roller-coaster\/"},"author":{"name":"Jeremy Price","@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015"},"headline":"Tommy Roberts Q&#038;A: Riding technology&#8217;s roller coaster","datePublished":"2023-12-11T19:19:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/tommy-roberts-qa-riding-technologys-roller-coaster\/"},"wordCount":1856,"image":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/tommy-roberts-qa-riding-technologys-roller-coaster\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/12\/Coneycyclone2.jpg","articleSection":["Spotlight Stories"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/tommy-roberts-qa-riding-technologys-roller-coaster\/","url":"https:\/\/www.hoosierenergy.com\/news-resources\/tommy-roberts-qa-riding-technologys-roller-coaster\/","name":"Entrevista com Tommy Roberts: A montanha-russa da tecnologia - Hoosier Energy","isPartOf":{"@id":"https:\/\/www.hoosierenergy.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/tommy-roberts-qa-riding-technologys-roller-coaster\/#primaryimage"},"image":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/tommy-roberts-qa-riding-technologys-roller-coaster\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/12\/Coneycyclone2.jpg","datePublished":"2023-12-11T19:19:30+00:00","author":{"@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015"},"description":"Tommy Roberts, da Hoosier Energy, ajuda a cooperativa a lidar com os altos e baixos da tecnologia no setor de energia el\u00e9trica.","breadcrumb":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/tommy-roberts-qa-riding-technologys-roller-coaster\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hoosierenergy.com\/news-resources\/tommy-roberts-qa-riding-technologys-roller-coaster\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/tommy-roberts-qa-riding-technologys-roller-coaster\/#primaryimage","url":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/12\/Coneycyclone2.jpg","contentUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/12\/Coneycyclone2.jpg","width":1778,"height":712},{"@type":"BreadcrumbList","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/tommy-roberts-qa-riding-technologys-roller-coaster\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hoosierenergy.com\/"},{"@type":"ListItem","position":2,"name":"Tommy Roberts Q&#038;A: Riding technology&#8217;s roller coaster"}]},{"@type":"WebSite","@id":"https:\/\/www.hoosierenergy.com\/#website","url":"https:\/\/www.hoosierenergy.com\/","name":"Energia Hoosier","description":"Alimentando a Comunidade","alternateName":"Hoosier Energy Rural Electric Cooperative, Inc.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hoosierenergy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015","name":"Jeremy Price"}]}},"date_formatted":"Dezembro 11, 2023","category":{"term_id":18,"name":"Spotlight Stories","slug":"spotlight-stories","term_group":0,"term_taxonomy_id":18,"taxonomy":"category","description":"","parent":0,"count":206,"filter":"raw"},"thumbnails":{"default":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/12\/Coneycyclone2.jpg","video":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/12\/Coneycyclone2.jpg"},"gallery":null,"video":null,"_links":{"self":[{"href":"https:\/\/www.hoosierenergy.com\/pt\/wp-json\/wp\/v2\/posts\/14593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoosierenergy.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoosierenergy.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/pt\/wp-json\/wp\/v2\/comments?post=14593"}],"version-history":[{"count":0,"href":"https:\/\/www.hoosierenergy.com\/pt\/wp-json\/wp\/v2\/posts\/14593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/pt\/wp-json\/wp\/v2\/media\/14594"}],"wp:attachment":[{"href":"https:\/\/www.hoosierenergy.com\/pt\/wp-json\/wp\/v2\/media?parent=14593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/pt\/wp-json\/wp\/v2\/categories?post=14593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/pt\/wp-json\/wp\/v2\/tags?post=14593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}