{"id":21171,"date":"2025-06-10T10:37:06","date_gmt":"2025-06-10T15:37:06","guid":{"rendered":"https:\/\/www.hoosierenergy.com\/?p=21171"},"modified":"2025-07-09T15:35:27","modified_gmt":"2025-07-09T20:35:27","slug":"pardue-goes-back-to-school-after-three-decades","status":"publish","type":"post","link":"https:\/\/www.hoosierenergy.com\/fr\/news-resources\/pardue-goes-back-to-school-after-three-decades\/","title":{"rendered":"Pardue retourne \u00e0 l&#039;\u00e9cole apr\u00e8s trois d\u00e9cennies"},"content":{"rendered":"<p>Cela faisait trois d\u00e9cennies que Trina Pardue n\u2019\u00e9tait plus \u00e0 l\u2019\u00e9cole.<\/p>\n<p>&nbsp;<\/p>\n<p>Mais \u00e0 sa grande surprise, retourner \u00e0 l&#039;\u00e9cole fut une exp\u00e9rience agr\u00e9able. Tellement agr\u00e9able que ce qui devait \u00eatre une br\u00e8ve visite pour obtenir un certificat en \u00e9v\u00e9nements sp\u00e9ciaux s&#039;est transform\u00e9 en presque deux ans et en un dipl\u00f4me d&#039;associ\u00e9 en administration h\u00f4teli\u00e8re \u00e0 Ivy Tech.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00ab J&#039;ai commenc\u00e9 \u00e0 suivre les cours et j&#039;ai vraiment ador\u00e9 \u00bb, a d\u00e9clar\u00e9 Pardue, responsable des \u00e9v\u00e9nements chez Hoosier Energy. \u00ab J&#039;avais de bons r\u00e9sultats, puis j&#039;ai r\u00e9alis\u00e9 que j&#039;\u00e9tais tout proche d&#039;obtenir un autre dipl\u00f4me, \u00e0 seulement six ou huit cours. C&#039;est donc ce que j&#039;ai d\u00e9cid\u00e9 de faire. \u00bb<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_21173\" style=\"width: 305px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-21173\" class=\"wp-image-21173\" src=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/Trina_limestone-225x300.jpg\" alt=\"\" width=\"295\" height=\"393\" srcset=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/Trina_limestone-225x300.jpg 225w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/Trina_limestone-768x1024.jpg 768w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/Trina_limestone-1152x1536.jpg 1152w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/Trina_limestone-9x12.jpg 9w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/Trina_limestone.jpg 1512w\" sizes=\"auto, (max-width: 295px) 100vw, 295px\" \/><p id=\"caption-attachment-21173\" class=\"wp-caption-text\">Trina Pardue, responsable des \u00e9v\u00e9nements chez Hoosier Energy, a obtenu son dipl\u00f4me d&#039;associ\u00e9 en administration h\u00f4teli\u00e8re ce printemps.<\/p><\/div>\n<p>Elle a obtenu son dipl\u00f4me de comptabilit\u00e9 en d\u00e9but de carri\u00e8re chez Hoosier Energy. Au fil du temps, Pardue a appris le graphisme en autodidacte, une comp\u00e9tence qui lui a ouvert la voie vers le service Communication, o\u00f9 elle s&#039;est rapidement plong\u00e9e dans l&#039;organisation d&#039;\u00e9v\u00e9nements.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00ab J&#039;ai vraiment trouv\u00e9 que c&#039;\u00e9tait mon cr\u00e9neau \u00bb, a-t-elle d\u00e9clar\u00e9. \u00ab J&#039;aime aider les gens, et c&#039;est pourquoi mon travail me convient parfaitement. Je contribue \u00e0 rassembler les gens pour diverses raisons, qu&#039;il s&#039;agisse de d\u00e9jeuners-conf\u00e9rences \u00e9ducatifs ou d&#039;aide \u00e0 la communaut\u00e9. C&#039;est mon c\u0153ur battant. \u00bb<\/p>\n<p>&nbsp;<\/p>\n<p>En trouvant ce cr\u00e9neau, Pardue a \u00e9t\u00e9 promue \u00e0 son poste actuel de responsable des \u00e9v\u00e9nements \u00e0 l&#039;automne 2023.<\/p>\n<p>&nbsp;<\/p>\n<p>C&#039;est \u00e0 peu pr\u00e8s \u00e0 la m\u00eame \u00e9poque qu&#039;elle a d\u00e9cid\u00e9 de poursuivre ses \u00e9tudes, aid\u00e9e par le programme de remboursement des frais de scolarit\u00e9 de Hoosier Energy.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00ab Ce sont les formations en leadership de Bell qui ont \u00e9veill\u00e9 mon int\u00e9r\u00eat pour l&#039;apprentissage \u00bb, explique Pardue. \u00ab J&#039;y ai beaucoup appris, et j&#039;ai \u00e9galement suivi le programme Leadership Edge de l&#039;IEC. Ces deux formations ont raviv\u00e9 mon int\u00e9r\u00eat pour l&#039;apprentissage. \u00bb<\/p>\n<p>&nbsp;<\/p>\n<p>Initialement, elle s&#039;\u00e9tait inscrite \u00e0 l&#039;Universit\u00e9 de l&#039;Indiana, mais ses conseillers p\u00e9dagogiques lui ont indiqu\u00e9 qu&#039;elle \u00e9tait surqualifi\u00e9e pour leur programme. Ivy Tech proposait un programme l\u00e9g\u00e8rement diff\u00e9rent, incluant la restauration lors d&#039;\u00e9v\u00e9nements sp\u00e9ciaux.<\/p>\n<p>&nbsp;<\/p>\n<p>Le premier cours de Pardue \u00e9tait Introduction \u00e0 l&#039;hospitalit\u00e9, qui comprenait beaucoup d&#039;histoire - plus qu&#039;elle ne voulait en savoir.<\/p>\n<p>&nbsp;<\/p>\n<p>Cependant, le cours suivant \u00e9tait ax\u00e9 sur les \u00e9v\u00e9nements sp\u00e9ciaux et Pardue s&#039;est soudainement senti comme chez lui.<\/p>\n<p>&nbsp;<\/p>\n<p>Elle passait ses soir\u00e9es ainsi que ses samedis et dimanches apr\u00e8s-midi \u00e0 faire ses devoirs aux c\u00f4t\u00e9s de sa fille, alors en terminale. Et lorsque sa camarade d&#039;\u00e9tudes est partie \u00e0 l&#039;universit\u00e9 l&#039;automne dernier, Pardue a acc\u00e9l\u00e9r\u00e9 le rythme.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00ab J&#039;ai d\u00e9cid\u00e9 de m&#039;inscrire \u00e0 temps plein, car j&#039;\u00e9tais dans la derni\u00e8re ligne droite \u00bb, a d\u00e9clar\u00e9 Pardue. \u00ab Et comme ma fille \u00e9tait partie, cela a combl\u00e9 le vide. \u00bb<\/p>\n<p>&nbsp;<\/p>\n<p>La plupart de ces cours \u00e9taient en ligne, mais deux \u00e9taient des cours en personne, ce qui a propuls\u00e9 Pardue vers un nouveau territoire.<\/p>\n<p>&nbsp;<\/p>\n<p>L&#039;une d&#039;elles \u00e9tait serveuse dans un restaurant gastronomique du centre-ville d&#039;Indianapolis. Outre les cours classiques, elle a suivi une formation pratique en situation r\u00e9elle o\u00f9 elle a occup\u00e9 divers postes en salle, notamment celui d&#039;h\u00f4tesse, de serveuse et de g\u00e9rante de service.<\/p>\n<p>&nbsp;<\/p>\n<p>L&#039;autre, \u00e0 Bloomington, \u00e9tait un cours de cuisine dont le projet final consistait \u00e0 pr\u00e9parer un repas complet. Celui de Pardue proposait du poulet frit, du riz pilaf et des asperges vapeur\u00a0; ce fut un succ\u00e8s.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00ab Le point positif de cette exp\u00e9rience, c&#039;est de voir l&#039;envers du d\u00e9cor \u00bb, a-t-elle d\u00e9clar\u00e9. \u00ab J&#039;ai pu observer le point de vue du lieu, de la restauration et des boissons, ainsi que celui de l&#039;h\u00f4tellerie gr\u00e2ce \u00e0 mon stage au Homewood Suites de Bloomington. \u00bb<\/p>\n<p>&nbsp;<\/p>\n<p>Apr\u00e8s avoir effectu\u00e9 un certain nombre d&#039;heures \u00e0 l&#039;h\u00f4tel, Pardue satisfera aux exigences de son programme MFP, du titre de Manager First Professional et d&#039;une certification en restauration et h\u00f4tellerie. Dans le cadre de ce programme, elle a d\u00e9j\u00e0 obtenu des certificats en ressources humaines, en service client, en contr\u00f4le des co\u00fbts alimentaires et en achats, ainsi que la certification ServSafe Food Protection Manager.<\/p>\n<p>&nbsp;<\/p>\n<p>Cela lui a certainement donn\u00e9 une vision diff\u00e9rente des choses lorsque Hoosier Energy a d\u00fb annuler sa r\u00e9union annuelle au French Lick Resort en raison de temp\u00eates dangereuses ce printemps.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00ab J&#039;ai pu comprendre le point de vue commercial et ce que cela impliquait pour French Lick \u00bb, a-t-elle d\u00e9clar\u00e9. \u00ab Cela facilite \u00e9galement la n\u00e9gociation de futurs contrats, car je connais leur point de vue et leur situation. \u00bb<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c9tonnamment, une grande partie de son travail scolaire co\u00efncidait avec celui de Pardue pour Hoosier Energy. En particulier, sa planification pour Electrify Indiana 2024 a \u00e9galement fait l&#039;objet d&#039;un projet scolaire de 58 pages, rendant ainsi ses apprentissages plus concrets et pertinents.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_21174\" style=\"width: 259px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-21174\" class=\"wp-image-21174\" src=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/Trina_cords-170x300.jpg\" alt=\"\" width=\"249\" height=\"439\" srcset=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/Trina_cords-170x300.jpg 170w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/Trina_cords-580x1024.jpg 580w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/Trina_cords-768x1356.jpg 768w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/Trina_cords-870x1536.jpg 870w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/Trina_cords-1160x2048.jpg 1160w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/Trina_cords-7x12.jpg 7w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/Trina_cords-scaled.jpg 1450w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/><p id=\"caption-attachment-21174\" class=\"wp-caption-text\">Trina Pardue, responsable des \u00e9v\u00e9nements chez Hoosier Energy, a obtenu son dipl\u00f4me avec mention d&#039;Ivy Tech avec son dipl\u00f4me d&#039;associ\u00e9 en administration h\u00f4teli\u00e8re ce printemps.<\/p><\/div>\n<p>En fin de compte, Pardue a eu la chance de faire quelque chose ce printemps qu&#039;elle n&#039;avait pas fait pour son premier dipl\u00f4me : marcher pour l&#039;obtention de son dipl\u00f4me.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00ab Pour mon dipl\u00f4me de comptabilit\u00e9, j&#039;\u00e9tais \u00e0 cet \u00e2ge o\u00f9 je voulais juste en finir et continuer ma vie \u00bb, a-t-elle d\u00e9clar\u00e9. \u00ab Cette fois, j&#039;ai envisag\u00e9 l&#039;\u00e9cole tr\u00e8s diff\u00e9remment. C&#039;\u00e9tait sous l&#039;angle d&#039;un projet ou d&#039;un emploi. Comme si je travaillais pour Hoosier, je me donnais \u00e0 fond, et c&#039;est ce que je faisais aussi en cours. \u00bb<\/p>\n<p>&nbsp;<\/p>\n<p>Pardue en a \u00e9t\u00e9 la preuve : elle a obtenu son dipl\u00f4me avec mention, avec une moyenne de 97 points. Sa r\u00e9ussite en classe t\u00e9moignait du plaisir qu&#039;elle avait \u00e0 reprendre ses \u00e9tudes et de l&#039;aide qu&#039;elle ressentait pour mieux faire son travail.<\/p>\n<p>&nbsp;<\/p>\n<p>Et ensuite ?<\/p>\n<p>&nbsp;<\/p>\n<p>\u00ab On n\u2019est jamais trop vieux pour apprendre \u00bb, a d\u00e9clar\u00e9 Pardue.<\/p>\n<p>&nbsp;<\/p>\n<p>Elle pr\u00e9voit de poursuivre son apprentissage en se pr\u00e9parant \u00e0 l&#039;examen CMP (Certified Meeting Professional), une certification internationale qui reconna\u00eet l&#039;expertise dans le secteur des r\u00e9unions et de l&#039;\u00e9v\u00e9nementiel. Cet examen atteste de ses connaissances en logistique, en planification d&#039;\u00e9v\u00e9nements et en bonnes pratiques du secteur.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00ab Avant m\u00eame de commencer \u00e0 suivre des cours, je disais que je n&#039;aimais pas simplement planifier des r\u00e9unions \u00bb, a d\u00e9clar\u00e9 Pardue. \u00ab J&#039;aime cr\u00e9er des exp\u00e9riences. Je veux que les choses soient m\u00e9morables. Vous savez, quand les gens repartent, je veux qu&#039;ils se sentent bien. Je veux que l&#039;\u00e9v\u00e9nement soit impressionnant et qu&#039;il harmonise l&#039;ensemble. Chaque petit d\u00e9tail fait toute la diff\u00e9rence. \u00bb<\/p>\n<p>&nbsp;<\/p>\n<p>Et il en va de m\u00eame pour plus de trois d\u00e9cennies entre les dipl\u00f4mes.<\/p>","protected":false},"excerpt":{"rendered":"Cela faisait trente ans que Trina Pardue n&#039;\u00e9tait plus all\u00e9e \u00e0 l&#039;\u00e9cole. Mais \u00e0 sa grande surprise, retourner \u00e0 l&#039;\u00e9cole fut une exp\u00e9rience agr\u00e9able. Tellement agr\u00e9able que ce qui \u00e9tait"},"author":7,"featured_media":21172,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-21171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spotlight-stories","category-18","description-off"],"acf":false,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Pardue goes back to school after three decades - Hoosier Energy<\/title>\r\n<meta name=\"description\" content=\"Hoosier Energy Events Manager Trina Pardue graduated from Ivy Tech with her Associate\u2019s Degree in Hospitality Administration. Read more.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.hoosierenergy.com\/fr\/news-resources\/pardue-goes-back-to-school-after-three-decades\/\" \/>\r\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Pardue goes back to school after three decades - Hoosier Energy\" \/>\r\n<meta property=\"og:description\" content=\"Hoosier Energy Events Manager Trina Pardue graduated from Ivy Tech with her Associate\u2019s Degree in Hospitality Administration. Read more.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.hoosierenergy.com\/fr\/news-resources\/pardue-goes-back-to-school-after-three-decades\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Hoosier Energy\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HoosierEnergy\" \/>\r\n<meta property=\"article:published_time\" content=\"2025-06-10T15:37:06+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-07-09T20:35:27+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/ivytechbloomington.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\r\n\t<meta property=\"og:image:height\" content=\"800\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Jeremy Price\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@hoosierenergy\" \/>\r\n<meta name=\"twitter:site\" content=\"@hoosierenergy\" \/>\r\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jeremy Price\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/pardue-goes-back-to-school-after-three-decades\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/pardue-goes-back-to-school-after-three-decades\\\/\"},\"author\":{\"name\":\"Jeremy Price\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\"},\"headline\":\"Pardue goes back to school after three decades\",\"datePublished\":\"2025-06-10T15:37:06+00:00\",\"dateModified\":\"2025-07-09T20:35:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/pardue-goes-back-to-school-after-three-decades\\\/\"},\"wordCount\":1060,\"image\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/pardue-goes-back-to-school-after-three-decades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/ivytechbloomington.jpg\",\"articleSection\":[\"Spotlight Stories\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/pardue-goes-back-to-school-after-three-decades\\\/\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/pardue-goes-back-to-school-after-three-decades\\\/\",\"name\":\"Pardue goes back to school after three decades - Hoosier Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/pardue-goes-back-to-school-after-three-decades\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/pardue-goes-back-to-school-after-three-decades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/ivytechbloomington.jpg\",\"datePublished\":\"2025-06-10T15:37:06+00:00\",\"dateModified\":\"2025-07-09T20:35:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\"},\"description\":\"Hoosier Energy Events Manager Trina Pardue graduated from Ivy Tech with her Associate\u2019s Degree in Hospitality Administration. Read more.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/pardue-goes-back-to-school-after-three-decades\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/pardue-goes-back-to-school-after-three-decades\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/pardue-goes-back-to-school-after-three-decades\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/ivytechbloomington.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/ivytechbloomington.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/pardue-goes-back-to-school-after-three-decades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hoosierenergy.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pardue goes back to school after three decades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#website\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/\",\"name\":\"Hoosier Energy\",\"description\":\"Powering Community\",\"alternateName\":\"Hoosier Energy Rural Electric Cooperative, Inc.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hoosierenergy.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\",\"name\":\"Jeremy Price\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pardue goes back to school after three decades - Hoosier Energy","description":"Hoosier Energy Events Manager Trina Pardue graduated from Ivy Tech with her Associate\u2019s Degree in Hospitality Administration. Read more.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hoosierenergy.com\/fr\/news-resources\/pardue-goes-back-to-school-after-three-decades\/","og_locale":"fr_FR","og_type":"article","og_title":"Pardue goes back to school after three decades - Hoosier Energy","og_description":"Hoosier Energy Events Manager Trina Pardue graduated from Ivy Tech with her Associate\u2019s Degree in Hospitality Administration. Read more.","og_url":"https:\/\/www.hoosierenergy.com\/fr\/news-resources\/pardue-goes-back-to-school-after-three-decades\/","og_site_name":"Hoosier Energy","article_publisher":"https:\/\/www.facebook.com\/HoosierEnergy","article_published_time":"2025-06-10T15:37:06+00:00","article_modified_time":"2025-07-09T20:35:27+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/ivytechbloomington.jpg","type":"image\/jpeg"}],"author":"Jeremy Price","twitter_card":"summary_large_image","twitter_creator":"@hoosierenergy","twitter_site":"@hoosierenergy","twitter_misc":{"\u00c9crit par":"Jeremy Price","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/pardue-goes-back-to-school-after-three-decades\/#article","isPartOf":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/pardue-goes-back-to-school-after-three-decades\/"},"author":{"name":"Jeremy Price","@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015"},"headline":"Pardue goes back to school after three decades","datePublished":"2025-06-10T15:37:06+00:00","dateModified":"2025-07-09T20:35:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/pardue-goes-back-to-school-after-three-decades\/"},"wordCount":1060,"image":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/pardue-goes-back-to-school-after-three-decades\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/ivytechbloomington.jpg","articleSection":["Spotlight Stories"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/pardue-goes-back-to-school-after-three-decades\/","url":"https:\/\/www.hoosierenergy.com\/news-resources\/pardue-goes-back-to-school-after-three-decades\/","name":"Pardue goes back to school after three decades - Hoosier Energy","isPartOf":{"@id":"https:\/\/www.hoosierenergy.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/pardue-goes-back-to-school-after-three-decades\/#primaryimage"},"image":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/pardue-goes-back-to-school-after-three-decades\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/ivytechbloomington.jpg","datePublished":"2025-06-10T15:37:06+00:00","dateModified":"2025-07-09T20:35:27+00:00","author":{"@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015"},"description":"Hoosier Energy Events Manager Trina Pardue graduated from Ivy Tech with her Associate\u2019s Degree in Hospitality Administration. Read more.","breadcrumb":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/pardue-goes-back-to-school-after-three-decades\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hoosierenergy.com\/news-resources\/pardue-goes-back-to-school-after-three-decades\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/pardue-goes-back-to-school-after-three-decades\/#primaryimage","url":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/ivytechbloomington.jpg","contentUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/ivytechbloomington.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/pardue-goes-back-to-school-after-three-decades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hoosierenergy.com\/"},{"@type":"ListItem","position":2,"name":"Pardue goes back to school after three decades"}]},{"@type":"WebSite","@id":"https:\/\/www.hoosierenergy.com\/#website","url":"https:\/\/www.hoosierenergy.com\/","name":"\u00c9nergie Hoosier","description":"Alimenter la communaut\u00e9","alternateName":"Hoosier Energy Rural Electric Cooperative, Inc.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hoosierenergy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015","name":"Jeremy Price"}]}},"date_formatted":"juin 10, 2025","category":{"term_id":18,"name":"Spotlight Stories","slug":"spotlight-stories","term_group":0,"term_taxonomy_id":18,"taxonomy":"category","description":"","parent":0,"count":206,"filter":"raw"},"thumbnails":{"default":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/ivytechbloomington.jpg","video":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2025\/06\/ivytechbloomington.jpg"},"gallery":null,"video":null,"_links":{"self":[{"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/posts\/21171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/comments?post=21171"}],"version-history":[{"count":0,"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/posts\/21171\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/media\/21172"}],"wp:attachment":[{"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/media?parent=21171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/categories?post=21171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/tags?post=21171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}