{"id":16698,"date":"2024-06-25T08:53:15","date_gmt":"2024-06-25T13:53:15","guid":{"rendered":"https:\/\/www.hoosierenergy.com\/?p=16698"},"modified":"2024-06-27T10:38:53","modified_gmt":"2024-06-27T15:38:53","slug":"skies-clear-for-energy-explorers-camp-at-sci","status":"publish","type":"post","link":"https:\/\/www.hoosierenergy.com\/fr\/news-resources\/skies-clear-for-energy-explorers-camp-at-sci\/","title":{"rendered":"Le ciel est d\u00e9gag\u00e9 pour le camp des explorateurs de l&#039;\u00e9nergie au SCI"},"content":{"rendered":"<p>Au cours de la derni\u00e8re d\u00e9cennie, le REMC du centre-sud de l&#039;Indiana a fait de son camp d&#039;explorateurs de l&#039;\u00e9nergie un incontournable du calendrier d&#039;un vendredi de la mi-juin.<\/p>\n<p>&nbsp;<\/p>\n<p>En 2023, le camp a \u00e9t\u00e9 frapp\u00e9 par un \u00e9v\u00e9nement historique ind\u00e9sirable, car la pire temp\u00eate \u2013 un derecho, en fait \u2013 \u00e0 avoir jamais frapp\u00e9 le territoire du SCI s&#039;est produite la nuit pr\u00e9c\u00e9dente.<\/p>\n<p>&nbsp;<\/p>\n<p>Cela a r\u00e9duit de moiti\u00e9 la fr\u00e9quentation du camp et a laiss\u00e9 une \u00e9quipe r\u00e9duite pour assumer les t\u00e2ches.<\/p>\n<p>&nbsp;<\/p>\n<p>Lorsque des temp\u00eates potentielles ont \u00e0 nouveau contourn\u00e9 la zone du SCI jeudi soir en 2024, Haley Jansen, sp\u00e9cialiste des communications des services aux membres, a pouss\u00e9 un soupir de soulagement par la suite.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00ab Cette ann\u00e9e, tout s\u2019est bien pass\u00e9 \u00bb, a-t-elle d\u00e9clar\u00e9. \u00ab Et cette ann\u00e9e, les campeurs ont pu tout voir. \u00bb<\/p>\n<p>&nbsp;<\/p>\n<p>Au total, 20 participants de la quatri\u00e8me \u00e0 la sixi\u00e8me ann\u00e9e ont commenc\u00e9 la journ\u00e9e par des pr\u00e9sentations et un bref historique du REMC avant de lancer les choses en faisant une activit\u00e9 de pot solaire avec Angela Dabney de Hoosier Energy.<\/p>\n<p>&nbsp;<\/p>\n<p>Puis est venue la d\u00e9monstration de la ligne \u00e9lectrique en direct, qui n\u2019\u00e9tait pas disponible il y a un an. Les monteurs de lignes du SCI ont utilis\u00e9 des accessoires allant des hot-dogs aux pamplemousses en passant par des ballons pour illustrer les dangers potentiels et la puissance des lignes \u00e9lectriques. Cela comprenait une le\u00e7on sur ce qu\u2019il faut faire si une voiture entre en contact avec des lignes \u00e9lectriques tomb\u00e9es. \u00ab L\u2019\u00e9lectricit\u00e9, c\u2019est comme des ondulations dans un \u00e9tang \u00bb, a-t-on expliqu\u00e9 aux campeurs.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_16700\" style=\"width: 405px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-16700\" class=\"wp-image-16700\" src=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/06\/Energy-Explorers-24_695a-300x200.jpg\" alt=\"Live line demo at Energy Explorers Camp\" width=\"395\" height=\"264\" srcset=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/06\/Energy-Explorers-24_695a-300x200.jpg 300w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/06\/Energy-Explorers-24_695a-1024x682.jpg 1024w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/06\/Energy-Explorers-24_695a-768x512.jpg 768w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/06\/Energy-Explorers-24_695a-18x12.jpg 18w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/06\/Energy-Explorers-24_695a.jpg 1364w\" sizes=\"auto, (max-width: 395px) 100vw, 395px\" \/><p id=\"caption-attachment-16700\" class=\"wp-caption-text\">Les monteurs de lignes SCI REMC effectuent une d\u00e9monstration de ligne en direct lors du camp Energy Explorers le 14 juin 2024.<\/p><\/div>\n<p>Une visite de l&#039;entrep\u00f4t SCI a suivi. Ils ont vu du vieux fil de cuivre, du nouveau fil d&#039;aluminium et du fil isol\u00e9 avec du cuivre et de l&#039;aluminium ainsi que des disjoncteurs \u00e0 r\u00e9enclenchement, des r\u00e9gulateurs et des fusibles. La visite s&#039;est arr\u00eat\u00e9e pour regarder des panneaux de signalisation \u00e0 LED, un camion avec une tari\u00e8re, un camion-nacelle, des rouleaux de fibre, des poteaux, une machine de jardin et plus encore.<\/p>\n<p>&nbsp;<\/p>\n<p>Apr\u00e8s une pause pour manger une pizza pour le d\u00e9jeuner, les campeurs ont \u00e9t\u00e9 divis\u00e9s en groupes de cinq pour se rendre \u00e0 diff\u00e9rentes stations toutes les demi-heures dans l&#039;apr\u00e8s-midi.<\/p>\n<p>&nbsp;<\/p>\n<p>Ces stations \u00e9taient :<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Fibre, o\u00f9 ils ont fabriqu\u00e9 leur propre version de fibre avec des pailles, une lumi\u00e8re et une batterie tout en visitant la remorque mobile de fibre.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Gestion de la v\u00e9g\u00e9tation, apprentissage de tout, depuis l&#039;\u00e9vitement des arbres avec des lignes \u00e9lectriques jusqu&#039;\u00e0 l&#039;\u00e9lagage des arbres et la connaissance des vignes et des choses comme l&#039;herbe \u00e0 puce, le ch\u00eane et le sumac.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Dispatch, o\u00f9 ils ont observ\u00e9 les moniteurs affichant la grille SCI et ont exp\u00e9riment\u00e9 la communication par talkie-walkie.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Camion nacelle, o\u00f9 chaque campeur a pu faire l&#039;exp\u00e9rience d&#039;un tour dans le camion nacelle de 60 pieds et arpenter la zone entourant le si\u00e8ge du SCI.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Station de drones, qui comprenait \u00e0 la fois un drone de ligne avec reconnaissance optique et imagerie thermique ainsi que le drone photo\/vid\u00e9o de Chris Johnson de Hoosier Energy.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>\u00ab Les enfants se sont plut\u00f4t bien d\u00e9brouill\u00e9s et nous avons fait en sorte qu&#039;ils n&#039;aient pratiquement pas de temps d&#039;arr\u00eat \u00bb, a d\u00e9clar\u00e9 Jansen.<\/p>\n<p>&nbsp;<\/p>\n<p>Un relais rapide entre les monteurs de lignes a permis de d\u00e9penser un peu d&#039;\u00e9nergie avant que la journ\u00e9e ne se termine par une pr\u00e9sentation du programme jeunesse d&#039;Ann Mears d&#039;Indiana Electric Cooperatives, suivie de photos de groupe, d&#039;un sac de cadeaux et d&#039;un r\u00e9capitulatif de ce que les campeurs ont appris.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00ab Notre \u00e9quipe du SCI a fait preuve d\u2019un travail d\u2019\u00e9quipe et d\u2019une collaboration exceptionnels cette ann\u00e9e et l\u2019ann\u00e9e derni\u00e8re, garantissant que tout se d\u00e9roule comme pr\u00e9vu \u00bb, a d\u00e9clar\u00e9 Jansen. \u00ab Pour l\u2019ann\u00e9e prochaine, que nous soyons confront\u00e9s \u00e0 des perturbations ou que nos plans se d\u00e9roulent sans probl\u00e8me, nous sommes pr\u00eats \u00e0 offrir une exp\u00e9rience amusante et \u00e9ducative aux enfants. \u00bb<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Lecteur vid\u00e9o YouTube\" src=\"https:\/\/www.youtube.com\/embed\/076CHYMxXmY?si=N-sErZcxB4bIobB5\" width=\"840\" height=\"420\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"Au cours de la derni\u00e8re d\u00e9cennie, le REMC du centre-sud de l&#039;Indiana a inscrit son camp d&#039;exploration de l&#039;\u00e9nergie \u00e0 son calendrier, un vendredi de la mi-juin. En 2023, le camp a eu lieu."},"author":7,"featured_media":16699,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-16698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spotlight-stories","category-18","description-off"],"acf":false,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Skies clear for Energy Explorers Camp at SCI - Hoosier Energy<\/title>\r\n<meta name=\"description\" content=\"Improved weather boosted attendance and the experience at South Central Indiana REMC&#039;s annual Energy Explorers Camp.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.hoosierenergy.com\/fr\/news-resources\/skies-clear-for-energy-explorers-camp-at-sci\/\" \/>\r\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Skies clear for Energy Explorers Camp at SCI - Hoosier Energy\" \/>\r\n<meta property=\"og:description\" content=\"Improved weather boosted attendance and the experience at South Central Indiana REMC&#039;s annual Energy Explorers Camp.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.hoosierenergy.com\/fr\/news-resources\/skies-clear-for-energy-explorers-camp-at-sci\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Hoosier Energy\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HoosierEnergy\" \/>\r\n<meta property=\"article:published_time\" content=\"2024-06-25T13:53:15+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2024-06-27T15:38:53+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/06\/Explorer24_IMG_4828.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1364\" \/>\r\n\t<meta property=\"og:image:height\" content=\"909\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Jeremy Price\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@hoosierenergy\" \/>\r\n<meta name=\"twitter:site\" content=\"@hoosierenergy\" \/>\r\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jeremy Price\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/skies-clear-for-energy-explorers-camp-at-sci\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/skies-clear-for-energy-explorers-camp-at-sci\\\/\"},\"author\":{\"name\":\"Jeremy Price\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\"},\"headline\":\"Skies clear for Energy Explorers Camp at SCI\",\"datePublished\":\"2024-06-25T13:53:15+00:00\",\"dateModified\":\"2024-06-27T15:38:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/skies-clear-for-energy-explorers-camp-at-sci\\\/\"},\"wordCount\":555,\"image\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/skies-clear-for-energy-explorers-camp-at-sci\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Explorer24_IMG_4828.jpg\",\"articleSection\":[\"Spotlight Stories\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/skies-clear-for-energy-explorers-camp-at-sci\\\/\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/skies-clear-for-energy-explorers-camp-at-sci\\\/\",\"name\":\"Skies clear for Energy Explorers Camp at SCI - Hoosier Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/skies-clear-for-energy-explorers-camp-at-sci\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/skies-clear-for-energy-explorers-camp-at-sci\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Explorer24_IMG_4828.jpg\",\"datePublished\":\"2024-06-25T13:53:15+00:00\",\"dateModified\":\"2024-06-27T15:38:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\"},\"description\":\"Improved weather boosted attendance and the experience at South Central Indiana REMC's annual Energy Explorers Camp.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/skies-clear-for-energy-explorers-camp-at-sci\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/skies-clear-for-energy-explorers-camp-at-sci\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/skies-clear-for-energy-explorers-camp-at-sci\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Explorer24_IMG_4828.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Explorer24_IMG_4828.jpg\",\"width\":1364,\"height\":909},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/skies-clear-for-energy-explorers-camp-at-sci\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hoosierenergy.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Skies clear for Energy Explorers Camp at SCI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#website\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/\",\"name\":\"Hoosier Energy\",\"description\":\"Powering Community\",\"alternateName\":\"Hoosier Energy Rural Electric Cooperative, Inc.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hoosierenergy.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\",\"name\":\"Jeremy Price\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ciel d\u00e9gag\u00e9 pour le camp Energy Explorers au SCI - Hoosier Energy","description":"L&#039;am\u00e9lioration des conditions m\u00e9t\u00e9orologiques a stimul\u00e9 la participation et enrichi l&#039;exp\u00e9rience au camp annuel Energy Explorers de South Central Indiana REMC.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hoosierenergy.com\/fr\/news-resources\/skies-clear-for-energy-explorers-camp-at-sci\/","og_locale":"fr_FR","og_type":"article","og_title":"Skies clear for Energy Explorers Camp at SCI - Hoosier Energy","og_description":"Improved weather boosted attendance and the experience at South Central Indiana REMC's annual Energy Explorers Camp.","og_url":"https:\/\/www.hoosierenergy.com\/fr\/news-resources\/skies-clear-for-energy-explorers-camp-at-sci\/","og_site_name":"Hoosier Energy","article_publisher":"https:\/\/www.facebook.com\/HoosierEnergy","article_published_time":"2024-06-25T13:53:15+00:00","article_modified_time":"2024-06-27T15:38:53+00:00","og_image":[{"width":1364,"height":909,"url":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/06\/Explorer24_IMG_4828.jpg","type":"image\/jpeg"}],"author":"Jeremy Price","twitter_card":"summary_large_image","twitter_creator":"@hoosierenergy","twitter_site":"@hoosierenergy","twitter_misc":{"\u00c9crit par":"Jeremy Price","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/skies-clear-for-energy-explorers-camp-at-sci\/#article","isPartOf":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/skies-clear-for-energy-explorers-camp-at-sci\/"},"author":{"name":"Jeremy Price","@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015"},"headline":"Skies clear for Energy Explorers Camp at SCI","datePublished":"2024-06-25T13:53:15+00:00","dateModified":"2024-06-27T15:38:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/skies-clear-for-energy-explorers-camp-at-sci\/"},"wordCount":555,"image":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/skies-clear-for-energy-explorers-camp-at-sci\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/06\/Explorer24_IMG_4828.jpg","articleSection":["Spotlight Stories"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/skies-clear-for-energy-explorers-camp-at-sci\/","url":"https:\/\/www.hoosierenergy.com\/news-resources\/skies-clear-for-energy-explorers-camp-at-sci\/","name":"Ciel d\u00e9gag\u00e9 pour le camp Energy Explorers au SCI - Hoosier Energy","isPartOf":{"@id":"https:\/\/www.hoosierenergy.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/skies-clear-for-energy-explorers-camp-at-sci\/#primaryimage"},"image":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/skies-clear-for-energy-explorers-camp-at-sci\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/06\/Explorer24_IMG_4828.jpg","datePublished":"2024-06-25T13:53:15+00:00","dateModified":"2024-06-27T15:38:53+00:00","author":{"@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015"},"description":"L&#039;am\u00e9lioration des conditions m\u00e9t\u00e9orologiques a stimul\u00e9 la participation et enrichi l&#039;exp\u00e9rience au camp annuel Energy Explorers de South Central Indiana REMC.","breadcrumb":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/skies-clear-for-energy-explorers-camp-at-sci\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hoosierenergy.com\/news-resources\/skies-clear-for-energy-explorers-camp-at-sci\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/skies-clear-for-energy-explorers-camp-at-sci\/#primaryimage","url":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/06\/Explorer24_IMG_4828.jpg","contentUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/06\/Explorer24_IMG_4828.jpg","width":1364,"height":909},{"@type":"BreadcrumbList","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/skies-clear-for-energy-explorers-camp-at-sci\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hoosierenergy.com\/"},{"@type":"ListItem","position":2,"name":"Skies clear for Energy Explorers Camp at SCI"}]},{"@type":"WebSite","@id":"https:\/\/www.hoosierenergy.com\/#website","url":"https:\/\/www.hoosierenergy.com\/","name":"\u00c9nergie Hoosier","description":"Alimenter la communaut\u00e9","alternateName":"Hoosier Energy Rural Electric Cooperative, Inc.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hoosierenergy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015","name":"Jeremy Price"}]}},"date_formatted":"juin 25, 2024","category":{"term_id":18,"name":"Spotlight Stories","slug":"spotlight-stories","term_group":0,"term_taxonomy_id":18,"taxonomy":"category","description":"","parent":0,"count":206,"filter":"raw"},"thumbnails":{"default":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/06\/Explorer24_IMG_4828.jpg","video":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/06\/Explorer24_IMG_4828.jpg"},"gallery":null,"video":null,"_links":{"self":[{"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/posts\/16698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/comments?post=16698"}],"version-history":[{"count":0,"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/posts\/16698\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/media\/16699"}],"wp:attachment":[{"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/media?parent=16698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/categories?post=16698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/tags?post=16698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}