{"id":14374,"date":"2023-11-28T11:00:45","date_gmt":"2023-11-28T16:00:45","guid":{"rendered":"https:\/\/www.hoosierenergy.com\/?p=14374"},"modified":"2023-11-28T11:00:45","modified_gmt":"2023-11-28T16:00:45","slug":"cooperatives-come-together-for-community-day-2023","status":"publish","type":"post","link":"https:\/\/www.hoosierenergy.com\/fr\/news-resources\/cooperatives-come-together-for-community-day-2023\/","title":{"rendered":"Les coop\u00e9ratives se rassemblent pour la Journ\u00e9e communautaire 2023"},"content":{"rendered":"<p>Chaque ann\u00e9e, le deuxi\u00e8me vendredi d&#039;octobre, les coop\u00e9ratives \u00e9lectriques de l&#039;Indiana participent collectivement \u00e0 la Journ\u00e9e communautaire.<\/p>\n<p>&nbsp;<\/p>\n<p>Cette ann\u00e9e, le 13 octobre n&#039;a pas fait exception \u00e0 la r\u00e8gle, car les coop\u00e9ratives de l&#039;\u00c9tat ont r\u00e9pondu \u00e0 divers besoins dans leur zone de service. Certaines coop\u00e9ratives ont organis\u00e9 leurs projets \u00e0 une date diff\u00e9rente, mais au total, 15 coop\u00e9ratives membres de Hoosier Energy ont montr\u00e9 leur int\u00e9r\u00eat pour la communaut\u00e9 de la mani\u00e8re suivante :<\/p>\n<p>&nbsp;<\/p>\n<p><strong>REMC DU COMT\u00c9 DE BARTHOLOMEW :<\/strong> Nous avons organis\u00e9 une journ\u00e9e d&#039;appr\u00e9ciation des membres du service au volant et une collecte de nourriture avec une carte-cadeau Chick-Fil-A $5 par passager en voiture, du ma\u00efs souffl\u00e9 frais et un parasurtenseur avec USB par v\u00e9hicule, apportant un aliment non p\u00e9rissable \u00e0 donner aux banques alimentaires locales.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>REMC DU COMT\u00c9 DE CLARK :<\/strong> J&#039;ai effectu\u00e9 des r\u00e9parations et effectu\u00e9 le nettoyage de la for\u00eat d&#039;\u00c9tat de Clark.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_14376\" style=\"width: 551px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-14376\" class=\"wp-image-14376\" src=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/11\/DM_PBJ.jpg\" alt=\"\" width=\"541\" height=\"550\" \/><p id=\"caption-attachment-14376\" class=\"wp-caption-text\">Les employ\u00e9s de Daviess-Martin REMC pr\u00e9parent des sandwichs au beurre de cacahu\u00e8te et \u00e0 la confiture dans le cadre de leurs efforts \u00e0 l&#039;occasion de la Journ\u00e9e communautaire.<\/p><\/div>\n<p><strong>DAVIESS-MARTIN REMC : <\/strong>Les employ\u00e9s ont pass\u00e9 leur matin\u00e9e \u00e0 l&#039;\u00e9glise New Beginnings \u00e0 Loogootee, pr\u00e9parant plus de 370 sandwichs au beurre de cacahu\u00e8te et \u00e0 la gel\u00e9e dans des sacs \u00e0 lunch \u00e0 livrer aux enfants dans le besoin dans le cadre du programme de d\u00e9jeuner du samedi.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>REMC DU COMT\u00c9 DE DECATUR : <\/strong>Les employ\u00e9s se sont port\u00e9s volontaires pour le d\u00e9partement des parcs du comt\u00e9 de Decatur, taillant et nettoyant les sentiers Charles Buell et r\u00e9alisant divers projets au refuge pour animaux du comt\u00e9 de Greensburg\/Decatur.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>HARRISON REMC: <\/strong>J&#039;ai particip\u00e9 \u00e0 la journ\u00e9e d&#039;\u00e9v\u00e9nements de r\u00e9paration du comt\u00e9 de Harrison, au cours de laquelle plus de 20 maisons ont \u00e9t\u00e9 r\u00e9par\u00e9es dans la communaut\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>REMC DU COMT\u00c9 DE HENRY :<\/strong> J&#039;ai accroch\u00e9 des lumi\u00e8res de No\u00ebl au palais de justice du comt\u00e9, d\u00e9cor\u00e9 des arbres au Arts Park et accroch\u00e9 des lumi\u00e8res \u00e0 la biblioth\u00e8que de New Castle.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>REMC DU COMT\u00c9 DE JACKSON :<\/strong> J&#039;ai pos\u00e9 des lignes \u00e9lectriques et j&#039;ai \u00e9galement ponc\u00e9 et teint\u00e9 les tables de pique-nique au Pershing Township Shelter House.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>JCREMC :<\/strong> J&#039;ai effectu\u00e9 un nettoyage d&#039;automne autour du centre de leadership de l&#039;Indiana FFA et j&#039;ai donn\u00e9 aux abris une nouvelle couche de peinture dans les parcs du comt\u00e9 de Johnson.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>REMC DU COMT\u00c9 D&#039;ORANGE :<\/strong> Nous avons organis\u00e9 un d\u00e9jeuner communautaire pour la Journ\u00e9e d&#039;appr\u00e9ciation des membres, avec des prix de pr\u00e9sence.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00c9NERGIE RUSHSHELBY :<\/strong> B\u00e9n\u00e9vole aux cimeti\u00e8res de Walnut Ridge et de Riverside \u00e0 Carthage, nettoyant les cl\u00f4tures, arrachant les mauvaises herbes, r\u00e9installant les pierres tombales et coupant les arbres.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>SCI REMC :<\/strong> J&#039;ai pass\u00e9 deux jours \u00e0 faire du b\u00e9n\u00e9volat \u00e0 Peden Farms et \u00e0 collecter des dons de produits de toilette pour des organismes \u00e0 but non lucratif locaux comme la Desert Rose Foundation Inc., le City Church Healing Hands Outreach Center et WellSpring qui soutiennent les familles, les femmes et les enfants confront\u00e9s au sans-abrisme, \u00e0 la pauvret\u00e9 et aux abus.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>SEI REMC :<\/strong> B\u00e9n\u00e9vole au parc national de Versailles, nettoyant les sentiers, les broussailles, la v\u00e9g\u00e9tation envahissante et tout ce qui se trouve le long du chemin.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>PUISSANCE DU SUD DE L&#039;INDIANA : <\/strong>Remplacement des poteaux au centre communautaire de Fulda et au stade de baseball de Fulda.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>REMC DE LA VALL\u00c9E DES EAUX BLANCHES :<\/strong> J&#039;ai travaill\u00e9 au parc naturel du comt\u00e9 d&#039;Union, aidant au nettoyage des broussailles, au d\u00e9chiquetage du bois, au d\u00e9sherbage et \u00e0 la construction d&#039;une nouvelle salle de bain.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>REMC GAGNEZ DE L&#039;\u00c9NERGIE :<\/strong> L&#039;\u00e9quipe s&#039;est port\u00e9e volontaire au parc des expositions du comt\u00e9 de Sullivan pour effectuer des travaux d&#039;am\u00e9nagement paysager, de construction de bancs et d&#039;\u00e9lagage d&#039;arbres.<\/p>","protected":false},"excerpt":{"rendered":"Chaque ann\u00e9e, le deuxi\u00e8me vendredi d&#039;octobre, les coop\u00e9ratives \u00e9lectriques de l&#039;Indiana participent collectivement \u00e0 la Journ\u00e9e communautaire. Cette ann\u00e9e, le 13 octobre n&#039;a pas fait exception\u00a0: les coop\u00e9ratives de tout l&#039;\u00c9tat se sont r\u00e9unies."},"author":7,"featured_media":14375,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-14374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spotlight-stories","category-18","description-off"],"acf":false,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Cooperatives come together for Community Day 2023 - Hoosier Energy<\/title>\r\n<meta name=\"description\" content=\"Hoosier Energy cooperatives took part in Indiana Electric Cooperatives&#039; Community Day 2023 with a number of community projects.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.hoosierenergy.com\/fr\/news-resources\/cooperatives-come-together-for-community-day-2023\/\" \/>\r\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Cooperatives come together for Community Day 2023 - Hoosier Energy\" \/>\r\n<meta property=\"og:description\" content=\"Hoosier Energy cooperatives took part in Indiana Electric Cooperatives&#039; Community Day 2023 with a number of community projects.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.hoosierenergy.com\/fr\/news-resources\/cooperatives-come-together-for-community-day-2023\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Hoosier Energy\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HoosierEnergy\" \/>\r\n<meta property=\"article:published_time\" content=\"2023-11-28T16:00:45+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/11\/WIN_fairgrounds.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Jeremy Price\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@hoosierenergy\" \/>\r\n<meta name=\"twitter:site\" content=\"@hoosierenergy\" \/>\r\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jeremy Price\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/cooperatives-come-together-for-community-day-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/cooperatives-come-together-for-community-day-2023\\\/\"},\"author\":{\"name\":\"Jeremy Price\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\"},\"headline\":\"Cooperatives come together for Community Day 2023\",\"datePublished\":\"2023-11-28T16:00:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/cooperatives-come-together-for-community-day-2023\\\/\"},\"wordCount\":469,\"image\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/cooperatives-come-together-for-community-day-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/WIN_fairgrounds.jpg\",\"articleSection\":[\"Spotlight Stories\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/cooperatives-come-together-for-community-day-2023\\\/\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/cooperatives-come-together-for-community-day-2023\\\/\",\"name\":\"Cooperatives come together for Community Day 2023 - Hoosier Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/cooperatives-come-together-for-community-day-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/cooperatives-come-together-for-community-day-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/WIN_fairgrounds.jpg\",\"datePublished\":\"2023-11-28T16:00:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\"},\"description\":\"Hoosier Energy cooperatives took part in Indiana Electric Cooperatives' Community Day 2023 with a number of community projects.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/cooperatives-come-together-for-community-day-2023\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/cooperatives-come-together-for-community-day-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/cooperatives-come-together-for-community-day-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/WIN_fairgrounds.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/WIN_fairgrounds.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/cooperatives-come-together-for-community-day-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hoosierenergy.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cooperatives come together for Community Day 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#website\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/\",\"name\":\"Hoosier Energy\",\"description\":\"Powering Community\",\"alternateName\":\"Hoosier Energy Rural Electric Cooperative, Inc.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hoosierenergy.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\",\"name\":\"Jeremy Price\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les coop\u00e9ratives se r\u00e9unissent pour la Journ\u00e9e communautaire 2023 - Hoosier Energy","description":"Les coop\u00e9ratives Hoosier Energy ont particip\u00e9 \u00e0 la Journ\u00e9e communautaire 2023 des coop\u00e9ratives \u00e9lectriques de l&#039;Indiana en r\u00e9alisant plusieurs projets communautaires.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hoosierenergy.com\/fr\/news-resources\/cooperatives-come-together-for-community-day-2023\/","og_locale":"fr_FR","og_type":"article","og_title":"Cooperatives come together for Community Day 2023 - Hoosier Energy","og_description":"Hoosier Energy cooperatives took part in Indiana Electric Cooperatives' Community Day 2023 with a number of community projects.","og_url":"https:\/\/www.hoosierenergy.com\/fr\/news-resources\/cooperatives-come-together-for-community-day-2023\/","og_site_name":"Hoosier Energy","article_publisher":"https:\/\/www.facebook.com\/HoosierEnergy","article_published_time":"2023-11-28T16:00:45+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/11\/WIN_fairgrounds.jpg","type":"image\/jpeg"}],"author":"Jeremy Price","twitter_card":"summary_large_image","twitter_creator":"@hoosierenergy","twitter_site":"@hoosierenergy","twitter_misc":{"\u00c9crit par":"Jeremy Price","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/cooperatives-come-together-for-community-day-2023\/#article","isPartOf":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/cooperatives-come-together-for-community-day-2023\/"},"author":{"name":"Jeremy Price","@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015"},"headline":"Cooperatives come together for Community Day 2023","datePublished":"2023-11-28T16:00:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/cooperatives-come-together-for-community-day-2023\/"},"wordCount":469,"image":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/cooperatives-come-together-for-community-day-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/11\/WIN_fairgrounds.jpg","articleSection":["Spotlight Stories"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/cooperatives-come-together-for-community-day-2023\/","url":"https:\/\/www.hoosierenergy.com\/news-resources\/cooperatives-come-together-for-community-day-2023\/","name":"Les coop\u00e9ratives se r\u00e9unissent pour la Journ\u00e9e communautaire 2023 - Hoosier Energy","isPartOf":{"@id":"https:\/\/www.hoosierenergy.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/cooperatives-come-together-for-community-day-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/cooperatives-come-together-for-community-day-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/11\/WIN_fairgrounds.jpg","datePublished":"2023-11-28T16:00:45+00:00","author":{"@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015"},"description":"Les coop\u00e9ratives Hoosier Energy ont particip\u00e9 \u00e0 la Journ\u00e9e communautaire 2023 des coop\u00e9ratives \u00e9lectriques de l&#039;Indiana en r\u00e9alisant plusieurs projets communautaires.","breadcrumb":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/cooperatives-come-together-for-community-day-2023\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hoosierenergy.com\/news-resources\/cooperatives-come-together-for-community-day-2023\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/cooperatives-come-together-for-community-day-2023\/#primaryimage","url":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/11\/WIN_fairgrounds.jpg","contentUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/11\/WIN_fairgrounds.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/cooperatives-come-together-for-community-day-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hoosierenergy.com\/"},{"@type":"ListItem","position":2,"name":"Cooperatives come together for Community Day 2023"}]},{"@type":"WebSite","@id":"https:\/\/www.hoosierenergy.com\/#website","url":"https:\/\/www.hoosierenergy.com\/","name":"\u00c9nergie Hoosier","description":"Alimenter la communaut\u00e9","alternateName":"Hoosier Energy Rural Electric Cooperative, Inc.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hoosierenergy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015","name":"Jeremy Price"}]}},"date_formatted":"novembre 28, 2023","category":{"term_id":18,"name":"Spotlight Stories","slug":"spotlight-stories","term_group":0,"term_taxonomy_id":18,"taxonomy":"category","description":"","parent":0,"count":206,"filter":"raw"},"thumbnails":{"default":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/11\/WIN_fairgrounds.jpg","video":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/11\/WIN_fairgrounds.jpg"},"gallery":null,"video":null,"_links":{"self":[{"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/posts\/14374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/comments?post=14374"}],"version-history":[{"count":0,"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/posts\/14374\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/media\/14375"}],"wp:attachment":[{"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/media?parent=14374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/categories?post=14374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/fr\/wp-json\/wp\/v2\/tags?post=14374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}