{"id":25284,"date":"2026-03-11T12:58:31","date_gmt":"2026-03-11T17:58:31","guid":{"rendered":"https:\/\/www.hoosierenergy.com\/?p=25284"},"modified":"2026-03-11T13:02:04","modified_gmt":"2026-03-11T18:02:04","slug":"qa-sowder-serves-year-as-ieda-chair","status":"publish","type":"post","link":"https:\/\/www.hoosierenergy.com\/es\/news-resources\/qa-sowder-serves-year-as-ieda-chair\/","title":{"rendered":"Preguntas y respuestas: Sowder cumple un a\u00f1o como presidente de IEDA"},"content":{"rendered":"<p>La Asociaci\u00f3n de Desarrollo Econ\u00f3mico de Indiana (IEDA, por sus siglas en ingl\u00e9s) ha estado vinculada durante mucho tiempo con Hoosier Energy, que formaba parte del grupo de empresas de servicios p\u00fablicos, bancos, bufetes de abogados, contables y otros pilares de la comunidad que ayudaron a fundar la organizaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>En 2025, Jeremy Sowders, gerente de desarrollo econ\u00f3mico, presidi\u00f3 la junta directiva de la IEDA y ayud\u00f3 a guiar al grupo durante un a\u00f1o de transici\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Recientemente, se sent\u00f3 a conversar sobre IEDA y su a\u00f1o al frente de la organizaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: \u00bfQu\u00e9 es la Asociaci\u00f3n de Desarrollo Econ\u00f3mico de Indiana y cu\u00e1nto tiempo lleva usted involucrado?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_12717\" style=\"width: 410px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-12717\" class=\"wp-image-12717\" src=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/09\/Jeremy-Sowders1.jpg\" alt=\"\" width=\"400\" height=\"400\" \/><p id=\"caption-attachment-12717\" class=\"wp-caption-text\">jeremy sowders<\/p><\/div>\n<p><strong>A:<\/strong> IEDA es una asociaci\u00f3n para profesionales del desarrollo econ\u00f3mico en todo Indiana. Re\u00fane a l\u00edderes de desarrollo econ\u00f3mico locales, del condado y estatales, junto con proveedores de servicios, empresas de servicios p\u00fablicos y otros interesados en el crecimiento de las comunidades y el fortalecimiento de las oportunidades laborales. Es una organizaci\u00f3n inclusiva, con la participaci\u00f3n de numerosos grupos.<\/p>\n<p>&nbsp;<\/p>\n<p>Mi primer d\u00eda en el Departamento de Comercio de Indiana en 2003 fue una experiencia inolvidable, y sigue siendo una de mis an\u00e9cdotas favoritas. Mi jefe me invit\u00f3 a un evento. En ese momento, se hab\u00eda implementado una congelaci\u00f3n de contrataciones y no estaba claro cu\u00e1nto tiempo conservar\u00eda el puesto. Me dijo: &quot;S\u00e9 que es tu primer d\u00eda, pero quiero que asistas a este evento y conozcas a las personas con las que trabajar\u00e1s en todo el estado&quot;. As\u00ed que estuve en la oficina un par de horas y luego cruc\u00e9 la calle para asistir a la conferencia anual de la IEDA, que reuni\u00f3 a m\u00e1s de 100 profesionales del desarrollo econ\u00f3mico que representaban a comunidades de todo Indiana.<\/p>\n<p>&nbsp;<\/p>\n<p>Caminar y hablar con la gente me abri\u00f3 los ojos sobre lo que les importaba, lo que suced\u00eda en sus comunidades y c\u00f3mo colaboraban con los funcionarios electos y otros l\u00edderes c\u00edvicos y empresariales. Fue divertido y estimulante. Ahora, m\u00e1s de 20 a\u00f1os despu\u00e9s, conservo amigos y colegas que conoc\u00ed aquel d\u00eda con quienes sigo trabajando y hablando a diario.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: \u00bfQu\u00e9 tiene de significativo lo que hace IEDA?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>A:<\/strong> Una organizaci\u00f3n como IEDA es m\u00e1s importante que nunca. Cuando comenc\u00e9 en esta profesi\u00f3n, a menudo se la llamaba &quot;cazar chimeneas&quot;. En aquel entonces, el desarrollo econ\u00f3mico consist\u00eda principalmente en atraer grandes inversiones industriales. El objetivo era atraer una gran f\u00e1brica a la ciudad para crear empleos. Esas inversiones fortalec\u00edan las comunidades, ampliaban la base impositiva y beneficiaban a todos. En los \u00faltimos 20 a\u00f1os, la situaci\u00f3n ha cambiado, y ahora se espera que los profesionales del desarrollo econ\u00f3mico hagan mucho m\u00e1s: desde el desarrollo de la fuerza laboral y la atracci\u00f3n de talento hasta la revitalizaci\u00f3n del centro de la ciudad, sin dejar de atraer y retener a las principales empresas.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: \u00bfC\u00f3mo interact\u00faa Hoosier Energy con IEDA?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>A: <\/strong>Hoosier Energy fue uno de los primeros miembros de IEDA. Los proveedores de servicios, entre los que se incluyen empresas de servicios p\u00fablicos, ferrocarriles, bancos y bufetes de abogados, se unieron a los primeros profesionales del desarrollo econ\u00f3mico y a los funcionarios electos para ayudar a legitimar la profesi\u00f3n y ampliar la base de profesionales en todo el estado.<\/p>\n<p>&nbsp;<\/p>\n<p>Esa colaboraci\u00f3n contribuy\u00f3 al surgimiento de IEDA. IEDA se basaba en la idea de que cuando una nueva empresa construye una instalaci\u00f3n en una comunidad, crea empleos y aumenta la demanda de servicios como servicios p\u00fablicos, bancos y otros socios locales.<\/p>\n<p>&nbsp;<\/p>\n<p>Tambi\u00e9n quiero reconocer la labor de Harold Gutzwiller, director de desarrollo econ\u00f3mico de Hoosier Energy, un defensor de larga trayectoria de IEDA y de la profesi\u00f3n del desarrollo econ\u00f3mico. Todos los que formamos parte de este departamento \u2014Harold, Jeff Pipkin y yo\u2014 comenzamos trabajando en organizaciones de desarrollo econ\u00f3mico locales, regionales o estatales, apoyando a las comunidades antes de incorporarnos a Hoosier Energy. Ahora apoyamos a nuestros miembros y a sus comunidades.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: \u00bfCu\u00e1l era su tarea como presidente?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>A: <\/strong>Mi gesti\u00f3n como presidenta se centr\u00f3 en el renacimiento y en el establecimiento de un plan para la sostenibilidad a largo plazo, a la vez que brindaba valor y apoyo a nuestros miembros. Gran parte de nuestro tiempo y energ\u00eda el a\u00f1o pasado se dedic\u00f3 a reinventar IEDA.<\/p>\n<p>&nbsp;<\/p>\n<p>Analizamos la trayectoria de IEDA durante los \u00faltimos 20 o 30 a\u00f1os y aprovechamos lo que funcionaba. Identificamos los puntos fuertes a la vez que impuls\u00e1bamos a IEDA hacia una nueva direcci\u00f3n y la posicion\u00e1bamos para el crecimiento. Esto implic\u00f3 una nueva comunicaci\u00f3n, una nueva imagen de marca y un enfoque renovado en toda la organizaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>A finales del a\u00f1o pasado, nos reunimos y decidimos no aferrarnos al pasado. Nos comprometimos a evaluar la situaci\u00f3n actual de IEDA, d\u00f3nde podr\u00eda y deber\u00eda estar, y a centrar nuestros esfuerzos en ello.<\/p>\n<p>&nbsp;<\/p>\n<p>Eso nos llev\u00f3 a lo que estamos haciendo ahora, que es organizar sesiones de di\u00e1logo con nuestros miembros, una en cada rinc\u00f3n del estado.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: \u00bfQu\u00e9 tal disfrut\u00f3 de su a\u00f1o como presidente?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>A:<\/strong> En primer lugar, fue un honor representar a Hoosier Energy y a nuestros miembros a nivel estatal. Cada vez que hablaba en p\u00fablico, representaba a Hoosier Energy y ten\u00eda la oportunidad de explicar qui\u00e9nes somos, qu\u00e9 hacemos y c\u00f3mo apoyamos a las comunidades de Indiana.<\/p>\n<p>&nbsp;<\/p>\n<p>En general, fue una experiencia muy gratificante. Aprend\u00ed much\u00edsimo a nivel profesional. Fue un honor poder retribuir a la asociaci\u00f3n que me ense\u00f1\u00f3 a realizar este trabajo. Cuando asist\u00ed a mi primera reuni\u00f3n de IEDA, ten\u00eda muy poco conocimiento sobre la profesi\u00f3n del desarrollo econ\u00f3mico, pero las conversaciones y los contactos que establec\u00ed all\u00ed sentaron las bases del conocimiento y la perspectiva en los que me baso hoy.<\/p>\n<p>&nbsp;<\/p>\n<p>Siempre recordar\u00e9 con cari\u00f1o esta oportunidad, y creo que el trabajo que realizamos contribuy\u00f3 a fortalecer IEDA y a acercarla a su lema: Un Estado, Muchas Voces. Fue un a\u00f1o de transici\u00f3n, pero uno que produjo avances significativos y posicion\u00f3 a IEDA para un futuro a\u00fan mejor.<\/p>","protected":false},"excerpt":{"rendered":"The Indiana Economic Development Association (IEDA) has long been associated with Hoosier Energy, which was among the group of utilities, banks, law firms, accountants and other community pillars who helped"},"author":7,"featured_media":7345,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-25284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spotlight-stories","category-18","description-off"],"acf":false,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Q&amp;A: Sowder serves year as IEDA chair - Hoosier Energy<\/title>\r\n<meta name=\"description\" content=\"Hoosier Energy&#039;s Jeremy Sowders served as chair for the Indiana Economic Development Association (IEDA) in 2025.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.hoosierenergy.com\/es\/news-resources\/qa-sowder-serves-year-as-ieda-chair\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Q&amp;A: Sowder serves year as IEDA chair - Hoosier Energy\" \/>\r\n<meta property=\"og:description\" content=\"Hoosier Energy&#039;s Jeremy Sowders served as chair for the Indiana Economic Development Association (IEDA) in 2025.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.hoosierenergy.com\/es\/news-resources\/qa-sowder-serves-year-as-ieda-chair\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Hoosier Energy\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HoosierEnergy\" \/>\r\n<meta property=\"article:published_time\" content=\"2026-03-11T17:58:31+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2026-03-11T18:02:04+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2022\/12\/Shelby_TechPark_Econ.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1932\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1085\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Jeremy Price\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@hoosierenergy\" \/>\r\n<meta name=\"twitter:site\" content=\"@hoosierenergy\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jeremy Price\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/qa-sowder-serves-year-as-ieda-chair\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/qa-sowder-serves-year-as-ieda-chair\\\/\"},\"author\":{\"name\":\"Jeremy Price\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\"},\"headline\":\"Q&#038;A: Sowder serves year as IEDA chair\",\"datePublished\":\"2026-03-11T17:58:31+00:00\",\"dateModified\":\"2026-03-11T18:02:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/qa-sowder-serves-year-as-ieda-chair\\\/\"},\"wordCount\":926,\"image\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/qa-sowder-serves-year-as-ieda-chair\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Shelby_TechPark_Econ.jpg\",\"articleSection\":[\"Spotlight Stories\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/qa-sowder-serves-year-as-ieda-chair\\\/\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/qa-sowder-serves-year-as-ieda-chair\\\/\",\"name\":\"Q&A: Sowder serves year as IEDA chair - Hoosier Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/qa-sowder-serves-year-as-ieda-chair\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/qa-sowder-serves-year-as-ieda-chair\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Shelby_TechPark_Econ.jpg\",\"datePublished\":\"2026-03-11T17:58:31+00:00\",\"dateModified\":\"2026-03-11T18:02:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\"},\"description\":\"Hoosier Energy's Jeremy Sowders served as chair for the Indiana Economic Development Association (IEDA) in 2025.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/qa-sowder-serves-year-as-ieda-chair\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/qa-sowder-serves-year-as-ieda-chair\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/qa-sowder-serves-year-as-ieda-chair\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Shelby_TechPark_Econ.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Shelby_TechPark_Econ.jpg\",\"width\":1932,\"height\":1085},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/qa-sowder-serves-year-as-ieda-chair\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hoosierenergy.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Q&#038;A: Sowder serves year as IEDA chair\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#website\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/\",\"name\":\"Hoosier Energy\",\"description\":\"Powering Community\",\"alternateName\":\"Hoosier Energy Rural Electric Cooperative, Inc.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hoosierenergy.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\",\"name\":\"Jeremy Price\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Q&A: Sowder serves year as IEDA chair - Hoosier Energy","description":"Hoosier Energy's Jeremy Sowders served as chair for the Indiana Economic Development Association (IEDA) in 2025.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hoosierenergy.com\/es\/news-resources\/qa-sowder-serves-year-as-ieda-chair\/","og_locale":"es_ES","og_type":"article","og_title":"Q&A: Sowder serves year as IEDA chair - Hoosier Energy","og_description":"Hoosier Energy's Jeremy Sowders served as chair for the Indiana Economic Development Association (IEDA) in 2025.","og_url":"https:\/\/www.hoosierenergy.com\/es\/news-resources\/qa-sowder-serves-year-as-ieda-chair\/","og_site_name":"Hoosier Energy","article_publisher":"https:\/\/www.facebook.com\/HoosierEnergy","article_published_time":"2026-03-11T17:58:31+00:00","article_modified_time":"2026-03-11T18:02:04+00:00","og_image":[{"width":1932,"height":1085,"url":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2022\/12\/Shelby_TechPark_Econ.jpg","type":"image\/jpeg"}],"author":"Jeremy Price","twitter_card":"summary_large_image","twitter_creator":"@hoosierenergy","twitter_site":"@hoosierenergy","twitter_misc":{"Escrito por":"Jeremy Price","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/qa-sowder-serves-year-as-ieda-chair\/#article","isPartOf":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/qa-sowder-serves-year-as-ieda-chair\/"},"author":{"name":"Jeremy Price","@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015"},"headline":"Q&#038;A: Sowder serves year as IEDA chair","datePublished":"2026-03-11T17:58:31+00:00","dateModified":"2026-03-11T18:02:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/qa-sowder-serves-year-as-ieda-chair\/"},"wordCount":926,"image":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/qa-sowder-serves-year-as-ieda-chair\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2022\/12\/Shelby_TechPark_Econ.jpg","articleSection":["Spotlight Stories"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/qa-sowder-serves-year-as-ieda-chair\/","url":"https:\/\/www.hoosierenergy.com\/news-resources\/qa-sowder-serves-year-as-ieda-chair\/","name":"Q&A: Sowder serves year as IEDA chair - Hoosier Energy","isPartOf":{"@id":"https:\/\/www.hoosierenergy.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/qa-sowder-serves-year-as-ieda-chair\/#primaryimage"},"image":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/qa-sowder-serves-year-as-ieda-chair\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2022\/12\/Shelby_TechPark_Econ.jpg","datePublished":"2026-03-11T17:58:31+00:00","dateModified":"2026-03-11T18:02:04+00:00","author":{"@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015"},"description":"Hoosier Energy's Jeremy Sowders served as chair for the Indiana Economic Development Association (IEDA) in 2025.","breadcrumb":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/qa-sowder-serves-year-as-ieda-chair\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hoosierenergy.com\/news-resources\/qa-sowder-serves-year-as-ieda-chair\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/qa-sowder-serves-year-as-ieda-chair\/#primaryimage","url":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2022\/12\/Shelby_TechPark_Econ.jpg","contentUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2022\/12\/Shelby_TechPark_Econ.jpg","width":1932,"height":1085},{"@type":"BreadcrumbList","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/qa-sowder-serves-year-as-ieda-chair\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hoosierenergy.com\/"},{"@type":"ListItem","position":2,"name":"Q&#038;A: Sowder serves year as IEDA chair"}]},{"@type":"WebSite","@id":"https:\/\/www.hoosierenergy.com\/#website","url":"https:\/\/www.hoosierenergy.com\/","name":"Energ\u00eda de Hoosier","description":"Comunidad de energ\u00eda","alternateName":"Hoosier Energy Rural Electric Cooperative, Inc.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hoosierenergy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015","name":"Jeremy Price"}]}},"date_formatted":"marzo 11, 2026","category":{"term_id":18,"name":"Spotlight Stories","slug":"spotlight-stories","term_group":0,"term_taxonomy_id":18,"taxonomy":"category","description":"","parent":0,"count":202,"filter":"raw"},"thumbnails":{"default":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2022\/12\/Shelby_TechPark_Econ.jpg","video":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2022\/12\/Shelby_TechPark_Econ.jpg"},"gallery":null,"video":null,"_links":{"self":[{"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/posts\/25284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/comments?post=25284"}],"version-history":[{"count":0,"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/posts\/25284\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/media\/7345"}],"wp:attachment":[{"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/media?parent=25284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/categories?post=25284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/tags?post=25284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}