{"id":18076,"date":"2024-12-09T14:54:10","date_gmt":"2024-12-09T19:54:10","guid":{"rendered":"https:\/\/www.hoosierenergy.com\/?p=18076"},"modified":"2024-12-09T14:54:10","modified_gmt":"2024-12-09T19:54:10","slug":"bear-run-mine-no-grizzly-task-for-hoosier-energy","status":"publish","type":"post","link":"https:\/\/www.hoosierenergy.com\/es\/news-resources\/bear-run-mine-no-grizzly-task-for-hoosier-energy\/","title":{"rendered":"La mina Bear Run no es una tarea complicada para Hoosier Energy"},"content":{"rendered":"<p>La mina Bear Run en el condado de Sullivan es la mina a cielo abierto m\u00e1s grande del este de los Estados Unidos.<\/p>\n<p>&nbsp;<\/p>\n<p>Cuando la mina estuvo lista para trasladarse al oeste a principios de 2024, fue un gran trabajo para Hoosier Energy mover una l\u00ednea de transmisi\u00f3n de 69 kV del camino.<\/p>\n<p>&nbsp;<\/p>\n<p>Originalmente construida en abril de 1969, la l\u00ednea de transmisi\u00f3n vio 1,8 millas de postes de madera reemplazados por 2\u00bc millas de postes de acero utilizando una l\u00ednea conductora 477 en el transcurso de cinco semanas.<\/p>\n<p>&nbsp;<\/p>\n<p>Fue un esfuerzo de equipo desde el principio, comenzando con el l\u00edder del equipo ambiental Dave Appel y el especialista ambiental Tommy Harrison, quienes garantizaron que se cumplieran todos los requisitos de informes y cumplimiento.<\/p>\n<p>&nbsp;<\/p>\n<p>Mick Ruhe actu\u00f3 como enlace de construcci\u00f3n y se asoci\u00f3 con el gerente de construcci\u00f3n Alan Summers para trabajar en estrecha colaboraci\u00f3n con el contratista Hydaker Wheatlake en el proyecto.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_18078\" style=\"width: 310px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-18078\" class=\"size-medium wp-image-18078\" src=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/12\/Bear_Run_pic1-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/12\/Bear_Run_pic1-300x225.jpg 300w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/12\/Bear_Run_pic1-1024x768.jpg 1024w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/12\/Bear_Run_pic1-768x576.jpg 768w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/12\/Bear_Run_pic1-1536x1152.jpg 1536w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/12\/Bear_Run_pic1-2048x1536.jpg 2048w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/12\/Bear_Run_pic1-16x12.jpg 16w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-18078\" class=\"wp-caption-text\">El proyecto de la mina Bear Run reemplaz\u00f3 1,8 millas de postes de madera por 2,25 millas de postes de acero.<\/p><\/div>\n<p>\u201cEstuve all\u00ed casi todos los d\u00edas, simplemente para controlar a los chicos y asegurarme de que tuvieran lo que necesitaban\u201d, dijo Ruhe. \u201cSi ten\u00edan una pregunta, yo les daba una respuesta y ellos segu\u00edan adelante\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>La clave para terminar el proyecto antes de lo previsto fue la creatividad del ingeniero s\u00e9nior de dise\u00f1o de l\u00edneas de transmisi\u00f3n, Luke McKinnley, quien utiliz\u00f3 un brazo Davit RUS est\u00e1ndar para trabajar con piezas que no habr\u00edan estado disponibles hasta el siguiente trimestre.<\/p>\n<p>&nbsp;<\/p>\n<p>Se perforaron agujeros con anticipaci\u00f3n, luego se colocaron los postes y los materiales en cada ubicaci\u00f3n, por lo que los equipos simplemente aparecieron y comenzaron a colocarlos en el suelo.<\/p>\n<p>&nbsp;<\/p>\n<p>Con el coordinador de la l\u00ednea del \u00e1rea, Brett Stephens, y su grupo asegur\u00e1ndose de que la l\u00ednea fuera segura para trabajar, la seguridad sigui\u00f3 siendo una prioridad m\u00e1xima.<\/p>\n<p>&nbsp;<\/p>\n<p>Al final fue un trabajo lo m\u00e1s eficiente posible.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cEl trabajo en equipo fue fant\u00e1stico\u201d, afirm\u00f3 el director de proyectos s\u00e9nior Kyle Eslinger. \u201cCuando tienes un plan y un gran equipo que puede ejecutarlo, mi trabajo resulta muy gratificante\u201d.<\/p>","protected":false},"excerpt":{"rendered":"La mina Bear Run, en el condado de Sullivan, es la mina a cielo abierto m\u00e1s grande del este de Estados Unidos. Cuando la mina estuvo lista para trasladarse al oeste a principios de 2024,..."},"author":7,"featured_media":18077,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-18076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spotlight-stories","category-18","description-off"],"acf":false,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Bear Run Mine no grizzly task for Hoosier Energy - Hoosier Energy<\/title>\r\n<meta name=\"description\" content=\"Bear Run Mine is the largest surface mine in the eastern United States, so moving a transmission line was no small task for Hoosier Energy.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.hoosierenergy.com\/es\/news-resources\/bear-run-mine-no-grizzly-task-for-hoosier-energy\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Bear Run Mine no grizzly task for Hoosier Energy - Hoosier Energy\" \/>\r\n<meta property=\"og:description\" content=\"Bear Run Mine is the largest surface mine in the eastern United States, so moving a transmission line was no small task for Hoosier Energy.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.hoosierenergy.com\/es\/news-resources\/bear-run-mine-no-grizzly-task-for-hoosier-energy\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Hoosier Energy\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HoosierEnergy\" \/>\r\n<meta property=\"article:published_time\" content=\"2024-12-09T19:54:10+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/12\/New_BearRun_pic2-scaled.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1700\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Jeremy Price\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@hoosierenergy\" \/>\r\n<meta name=\"twitter:site\" content=\"@hoosierenergy\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jeremy Price\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/bear-run-mine-no-grizzly-task-for-hoosier-energy\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/bear-run-mine-no-grizzly-task-for-hoosier-energy\\\/\"},\"author\":{\"name\":\"Jeremy Price\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\"},\"headline\":\"Bear Run Mine no grizzly task for Hoosier Energy\",\"datePublished\":\"2024-12-09T19:54:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/bear-run-mine-no-grizzly-task-for-hoosier-energy\\\/\"},\"wordCount\":332,\"image\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/bear-run-mine-no-grizzly-task-for-hoosier-energy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/New_BearRun_pic2-scaled.jpg\",\"articleSection\":[\"Spotlight Stories\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/bear-run-mine-no-grizzly-task-for-hoosier-energy\\\/\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/bear-run-mine-no-grizzly-task-for-hoosier-energy\\\/\",\"name\":\"Bear Run Mine no grizzly task for Hoosier Energy - Hoosier Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/bear-run-mine-no-grizzly-task-for-hoosier-energy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/bear-run-mine-no-grizzly-task-for-hoosier-energy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/New_BearRun_pic2-scaled.jpg\",\"datePublished\":\"2024-12-09T19:54:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\"},\"description\":\"Bear Run Mine is the largest surface mine in the eastern United States, so moving a transmission line was no small task for Hoosier Energy.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/bear-run-mine-no-grizzly-task-for-hoosier-energy\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/bear-run-mine-no-grizzly-task-for-hoosier-energy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/bear-run-mine-no-grizzly-task-for-hoosier-energy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/New_BearRun_pic2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/New_BearRun_pic2-scaled.jpg\",\"width\":2560,\"height\":1700,\"caption\":\"The Bear Run Mine project replaced 1.8 miles of wood poles with 2.25 miles of steel poles.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/bear-run-mine-no-grizzly-task-for-hoosier-energy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hoosierenergy.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bear Run Mine no grizzly task for Hoosier Energy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#website\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/\",\"name\":\"Hoosier Energy\",\"description\":\"Powering Community\",\"alternateName\":\"Hoosier Energy Rural Electric Cooperative, Inc.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hoosierenergy.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\",\"name\":\"Jeremy Price\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bear Run Mine no grizzly task for Hoosier Energy - Hoosier Energy","description":"Bear Run Mine is the largest surface mine in the eastern United States, so moving a transmission line was no small task for Hoosier Energy.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hoosierenergy.com\/es\/news-resources\/bear-run-mine-no-grizzly-task-for-hoosier-energy\/","og_locale":"es_ES","og_type":"article","og_title":"Bear Run Mine no grizzly task for Hoosier Energy - Hoosier Energy","og_description":"Bear Run Mine is the largest surface mine in the eastern United States, so moving a transmission line was no small task for Hoosier Energy.","og_url":"https:\/\/www.hoosierenergy.com\/es\/news-resources\/bear-run-mine-no-grizzly-task-for-hoosier-energy\/","og_site_name":"Hoosier Energy","article_publisher":"https:\/\/www.facebook.com\/HoosierEnergy","article_published_time":"2024-12-09T19:54:10+00:00","og_image":[{"width":2560,"height":1700,"url":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/12\/New_BearRun_pic2-scaled.jpg","type":"image\/jpeg"}],"author":"Jeremy Price","twitter_card":"summary_large_image","twitter_creator":"@hoosierenergy","twitter_site":"@hoosierenergy","twitter_misc":{"Escrito por":"Jeremy Price","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/bear-run-mine-no-grizzly-task-for-hoosier-energy\/#article","isPartOf":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/bear-run-mine-no-grizzly-task-for-hoosier-energy\/"},"author":{"name":"Jeremy Price","@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015"},"headline":"Bear Run Mine no grizzly task for Hoosier Energy","datePublished":"2024-12-09T19:54:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/bear-run-mine-no-grizzly-task-for-hoosier-energy\/"},"wordCount":332,"image":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/bear-run-mine-no-grizzly-task-for-hoosier-energy\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/12\/New_BearRun_pic2-scaled.jpg","articleSection":["Spotlight Stories"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/bear-run-mine-no-grizzly-task-for-hoosier-energy\/","url":"https:\/\/www.hoosierenergy.com\/news-resources\/bear-run-mine-no-grizzly-task-for-hoosier-energy\/","name":"Bear Run Mine no grizzly task for Hoosier Energy - Hoosier Energy","isPartOf":{"@id":"https:\/\/www.hoosierenergy.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/bear-run-mine-no-grizzly-task-for-hoosier-energy\/#primaryimage"},"image":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/bear-run-mine-no-grizzly-task-for-hoosier-energy\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/12\/New_BearRun_pic2-scaled.jpg","datePublished":"2024-12-09T19:54:10+00:00","author":{"@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015"},"description":"Bear Run Mine is the largest surface mine in the eastern United States, so moving a transmission line was no small task for Hoosier Energy.","breadcrumb":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/bear-run-mine-no-grizzly-task-for-hoosier-energy\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hoosierenergy.com\/news-resources\/bear-run-mine-no-grizzly-task-for-hoosier-energy\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/bear-run-mine-no-grizzly-task-for-hoosier-energy\/#primaryimage","url":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/12\/New_BearRun_pic2-scaled.jpg","contentUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/12\/New_BearRun_pic2-scaled.jpg","width":2560,"height":1700,"caption":"The Bear Run Mine project replaced 1.8 miles of wood poles with 2.25 miles of steel poles."},{"@type":"BreadcrumbList","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/bear-run-mine-no-grizzly-task-for-hoosier-energy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hoosierenergy.com\/"},{"@type":"ListItem","position":2,"name":"Bear Run Mine no grizzly task for Hoosier Energy"}]},{"@type":"WebSite","@id":"https:\/\/www.hoosierenergy.com\/#website","url":"https:\/\/www.hoosierenergy.com\/","name":"Energ\u00eda de Hoosier","description":"Comunidad de energ\u00eda","alternateName":"Hoosier Energy Rural Electric Cooperative, Inc.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hoosierenergy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015","name":"Jeremy Price"}]}},"date_formatted":"diciembre 9, 2024","category":{"term_id":18,"name":"Spotlight Stories","slug":"spotlight-stories","term_group":0,"term_taxonomy_id":18,"taxonomy":"category","description":"","parent":0,"count":206,"filter":"raw"},"thumbnails":{"default":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/12\/New_BearRun_pic2-scaled.jpg","video":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/12\/New_BearRun_pic2-scaled.jpg"},"gallery":null,"video":null,"_links":{"self":[{"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/posts\/18076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/comments?post=18076"}],"version-history":[{"count":0,"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/posts\/18076\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/media\/18077"}],"wp:attachment":[{"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/media?parent=18076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/categories?post=18076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/tags?post=18076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}