{"id":14089,"date":"2023-11-14T09:11:08","date_gmt":"2023-11-14T14:11:08","guid":{"rendered":"https:\/\/www.hoosierenergy.com\/?p=14089"},"modified":"2023-11-14T13:23:20","modified_gmt":"2023-11-14T18:23:20","slug":"megan-miller-qa-new-role-new-experience","status":"publish","type":"post","link":"https:\/\/www.hoosierenergy.com\/es\/news-resources\/megan-miller-qa-new-role-new-experience\/","title":{"rendered":"Preguntas y respuestas de Megan Miller: nuevo rol, nueva experiencia"},"content":{"rendered":"<p>Tarde o temprano, la vida trae cambios para todos. Para Megan Miller, aceptar el cambio ha sido un estilo de vida durante la mayor parte de dos d\u00e9cadas y no hay signos de ceder.<\/p>\n<p>&nbsp;<\/p>\n<p>Desde Minnesota hasta Florida e Indiana geogr\u00e1ficamente, desde atenci\u00f3n m\u00e9dica hasta experta en acondicionamiento f\u00edsico, administraci\u00f3n de empresas y m\u00e1s all\u00e1 en estudios, y una carrera en la que los t\u00edtulos de trabajo han cambiado tan r\u00e1pido como el clima en el estado de Hoosier, lo que a Miller le ha faltado en estabilidad lo ha compensado. en aventuras, incluyendo un marido y dos hijos para mantener el tiovivo girando fuera del trabajo.<\/p>\n<p>&nbsp;<\/p>\n<p>Recientemente se sent\u00f3 a hablar con GridLines sobre todas esas cosas, as\u00ed como sobre su \u00faltima encarnaci\u00f3n como Gerente de Mejora Continua y Experiencia del Empleado en Hoosier Energy.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: El t\u00edtulo del trabajo sigue cambiando, \u00bfcu\u00e1nto sigue cambiando lo que haces?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>A:<\/strong> La misma cantidad que el t\u00edtulo. Asum\u00ed el puesto de Coordinador de Experiencia del Empleado en julio de este a\u00f1o, y eso fue emocionante porque fue agregar algunas cosas de las que se hab\u00eda hablado durante un tiempo, hacer algunas cosas nuevas, prestar atenci\u00f3n a algunas cosas y luego, por otro lado, ya estaba involucrado. con el programa de Mejora Continua.<\/p>\n<p>&nbsp;<\/p>\n<p>Con este cambio, la Experiencia del Empleado y la Mejora Continua han vuelto a evolucionar. Todav\u00eda estoy tratando de abrazarlo y tener una idea de lo que est\u00e1 pasando, hacia d\u00f3nde queremos ir y qu\u00e9 oportunidades tenemos. Con suerte, las cosas se calmar\u00e1n, pero los dos realmente van de la mano cuando lo piensas.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: Desde el punto de vista de la Mejora Continua, \u00bfcu\u00e1l es la pr\u00f3xima evoluci\u00f3n?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>A:<\/strong> Con un programa completamente nuevo, hay que reunir a todos en torno a \u00e9l, hay que comunicar el programa, hay que capacitar a todos. Nosotros hicimos eso.<\/p>\n<p>&nbsp;<\/p>\n<p>Ahora quiero tomar la gran base que construimos y continuar. Llevamos a\u00f1os realizando mejoras continuas. No siempre lo llamamos as\u00ed, pero hay una serie de proyectos que puedes ver en cada departamento y que se crearon con ese esp\u00edritu: \u00bfC\u00f3mo podemos hacer las cosas mejor? \u00bfC\u00f3mo podemos ser m\u00e1s eficientes? \u00bfC\u00f3mo podemos ser m\u00e1s colaborativos?<\/p>\n<p>&nbsp;<\/p>\n<p>Las cosas han evolucionado de manera m\u00e1s formal, primero como una prioridad estrat\u00e9gica y ahora como el Programa de Mejora Continua de la Electricidad Rural (RECIP, por sus siglas en ingl\u00e9s) con camisas, bol\u00edgrafos y todo el asunto, pero veo que la CI se dirige a poder aprovechar algunas de las herramientas que tenemos ahora. y cuando los grupos de trabajo tienen un problema, tienen el proceso que necesitan mejorar. Me gustar\u00eda pensar que el programa CI podr\u00eda ayudar a reunir a las personas adecuadas en la sala, facilitar una discusi\u00f3n (en cierto modo investigativa) pero realmente ayudar a las personas a recorrer el proceso de qu\u00e9 estamos haciendo ahora, c\u00f3mo ser\u00eda cambiar y C\u00f3mo podemos cambiar esto.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_14090\" style=\"width: 509px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-14090\" class=\"wp-image-14090\" src=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/11\/Megan_CI_training1.jpg\" alt=\"Megan Miller provides instructions during Continuous Improvement training at Hoosier Energy.\" width=\"499\" height=\"369\" \/><p id=\"caption-attachment-14090\" class=\"wp-caption-text\">Megan Miller brinda instrucciones durante la capacitaci\u00f3n de Mejora Continua en Hoosier Energy.<\/p><\/div>\n<p>En definitiva, es un programa muy orientado a soluciones. Siempre hay cosas que podemos hacer mejor, no importa lo buenos que seamos. Mientras haya cosas que mejorar, la mejora continua es relevante.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: En lo que respecta a la Experiencia del Empleado, \u00bfen qu\u00e9 se diferencia de los Recursos Humanos tradicionales?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>A:<\/strong> Se trata de hacer de Hoosier Energy un mejor lugar para trabajar. \u00bfC\u00f3mo podemos seguir mejorando las experiencias de los empleados? No hay una respuesta f\u00e1cil para esto y no es una soluci\u00f3n \u00fanica para todos, pero hay algunos temas generales all\u00ed.<\/p>\n<p>&nbsp;<\/p>\n<p>La experiencia de los empleados est\u00e1 relacionada con RR.HH. y en este puesto, colaboro con RR.HH. en muchas de esas iniciativas que la experiencia de los empleados est\u00e1 abriendo. Por ejemplo, incorporaci\u00f3n. Renovar el proceso de incorporaci\u00f3n es un gran problema ya que, adem\u00e1s de la entrevista y la oferta, es el comienzo del viaje de alguien en Hoosier. Podr\u00edamos llamar a la experiencia de los empleados un proceso de incorporaci\u00f3n y desvinculaci\u00f3n, s\u00f3lo para simplificar. El viaje que atraviesan los empleados y todos los puntos de contacto que se encuentran a lo largo de ese camino, un buen n\u00famero de ellos tienen que ver con RR.HH., desde n\u00f3mina y beneficios hasta capacitaci\u00f3n y educaci\u00f3n, pero no es exclusivo de RR.HH.<\/p>\n<p>&nbsp;<\/p>\n<p>Mejorar la experiencia de los empleados no lo hace una sola persona. Ni siquiera lo hace un departamento. Se necesita que las personas cambien su forma de pensar y que todos est\u00e9n dispuestos a hacer las cosas de manera diferente; considere que lo que podr\u00eda haber funcionado para usted puede no funcionar para la siguiente persona.<\/p>\n<p>&nbsp;<\/p>\n<p>Observe tambi\u00e9n el hecho de que lo que la gente quiere en un trabajo, lo que la gente quiere en el lugar de trabajo ha cambiado. Necesitamos adaptarnos a eso. Esto es m\u00e1s grande que el esfuerzo de una sola persona o un departamento. As\u00ed es como la experiencia de los empleados es diferente a la de RRHH.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: \u00bfEn qu\u00e9 medida han influido los cambios causados por la COVID-19 en la experiencia de los empleados?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>A:<\/strong> Probablemente podr\u00eda hablar durante un par de horas sobre todas las razones por las que creo que es importante este puesto y prestarle especial atenci\u00f3n. Est\u00e1n todos los cambios obvios que trajo el COVID-19. Muchos de nosotros tenemos ahora un acuerdo de trabajo flexible, pero no todos nuestros empleados lo tienen. Hay un problema. \u00bfC\u00f3mo se equilibra y se comunica con personas que pueden trabajar desde casa todo el tiempo frente a personas que no necesariamente miran su correo electr\u00f3nico o su tel\u00e9fono?<\/p>\n<p>&nbsp;<\/p>\n<p>Tambi\u00e9n hay muchas cosas que no podemos ver y que a las personas les puede resultar dif\u00edcil articular. Parte de estar en un lugar de trabajo es experimentar inclusi\u00f3n y pertenencia, y eso es m\u00e1s dif\u00edcil de conseguir y de practicar. Incluso los gerentes se han preguntado: &quot;\u00bfC\u00f3mo gestiono a las personas en un entorno como este?&quot; y necesitamos poder ayudar con eso y hablar sobre las cosas dif\u00edciles. Se trata de abordar las cosas que puedes ver y abordar las cosas que no puedes ver.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: El mercado laboral en general tambi\u00e9n ha cambiado con las expectativas de la gente, \u00bfverdad?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>A:<\/strong> Las expectativas han cambiado y hoy en d\u00eda hay m\u00e1s diversidad en la fuerza laboral que nunca, comenzando por m\u00e1s generaciones. Tenemos cuatro generaciones en el lugar de trabajo en este momento, as\u00ed que lo que quieren todas esas generaciones y su experiencia laboral, c\u00f3mo fueron criados, c\u00f3mo quieren que se les comunique, su perspectiva, todo es muy diferente. Necesitamos aprender c\u00f3mo tener \u00e9xito juntos. Hoosier no sol\u00eda tener mucha rotaci\u00f3n. Eso ha cambiado. No dir\u00eda que tenemos mucho, pero ha aumentado. El panorama de la industria ha cambiado y el ritmo del cambio es diferente, lo que son factores externos fuera de Hoosier que tambi\u00e9n hacen que este puesto sea necesario.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: \u00bfQu\u00e9 lo llev\u00f3 por el camino hacia Hoosier Energy?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>A:<\/strong> Mi t\u00edtulo universitario es en ciencias del ejercicio. Quer\u00eda ser m\u00e9dico cuando era m\u00e1s joven, luego estudi\u00e9 qu\u00edmica en la universidad y eso me elimin\u00f3. Pero siempre tuve fascinaci\u00f3n por nuestros cuerpos y nuestra salud f\u00edsica. \u00bfC\u00f3mo podemos hacer lo que hacemos?<\/p>\n<p>&nbsp;<\/p>\n<p>Pens\u00e9 que iba a trabajar en la industria del fitness\/salud\/bienestar, pero al cabo de no muchos a\u00f1os me di cuenta de que estaba m\u00e1s interesado en las personas mismas y, a mayor escala, en lo que las motiva. \u00bfPor qu\u00e9 ante una misma situaci\u00f3n cada una de estas personas se comporta de manera diferente? Empec\u00e9 a interesarme por personas de un nivel diferente.<\/p>\n<p>&nbsp;<\/p>\n<p>Mientras trabajaba para un hospital en Florida, obtuve mi maestr\u00eda en negocios. No sab\u00eda lo que quer\u00eda hacer, pero quer\u00eda mantener abiertas mis opciones. Hab\u00eda ido de Minnesota a Florida a Indiana. Nosotros (esposo, dos hijos y dos perros) vivimos en Ellettsville, de donde es mi esposo, as\u00ed que cuando nos mudamos aqu\u00ed por primera vez, yo ten\u00eda estos dos t\u00edtulos y no quer\u00eda hacer ejercicio pero no sab\u00eda qu\u00e9 hacer, as\u00ed que Dud\u00e9 un rato. Me dediqu\u00e9 a la administraci\u00f3n de propiedades por un tiempo, pero termin\u00e9 trabajando como contratista en Hoosier hace nueve a\u00f1os, justo despu\u00e9s de que naciera mi primer hijo. De hecho, tuve mi entrevista para el trabajo una semana antes de dar a luz. Yo era... enorme. T\u00e9cnicamente estaba trabajando para el asesor de beneficios de Hoosier Energy como coordinador de bienestar en el lugar.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P: \u00bfC\u00f3mo pas\u00f3 del bienestar a la experiencia de los empleados y la mejora continua?<\/strong><\/p>\n<p>Inicialmente, estaba creando un programa e impartiendo sesiones educativas y desaf\u00edos para que las personas los hicieran, porque me apasionaba el fitness, el bienestar, la salud y ayudar a las personas a disfrutar la vida. Pero a lo largo de esos cuatro a\u00f1os, fui conociendo gente de toda la empresa. Y amaba a la gente de aqu\u00ed.<\/p>\n<p>&nbsp;<\/p>\n<p>Estaba casi listo para irme, solo porque ya no quer\u00eda estar en bienestar. Entonces se abri\u00f3 una oportunidad en Recursos Humanos, que era como, &#039;Oye, amo a la gente, todav\u00eda puedo ayudar a la gente, pero no ser\u00e1 influyendo en su salud f\u00edsica&#039;.<\/p>\n<p>&nbsp;<\/p>\n<p>Consegu\u00ed ese trabajo y luego agregu\u00e9 UKG a mi plato porque ten\u00eda el ancho de banda para encargarme de eso. Estaba haciendo muchas cosas en RR.HH., luego surgi\u00f3 el trabajo de Coordinador de Experiencia del Empleado a principios de este a\u00f1o, que era: &#039;Tomemos lo que est\u00e1s haciendo y sigamos mejor\u00e1ndolo, centr\u00e1ndonos en ciertas partes de RR.HH. como la incorporaci\u00f3n, formaci\u00f3n y desarrollo.&#039; Con el tiempo, espero prestar m\u00e1s atenci\u00f3n a la tutor\u00eda y las pasant\u00edas y dedicarme a la planificaci\u00f3n de la sucesi\u00f3n. Veo tantas oportunidades aqu\u00ed para cosas que no estamos haciendo que si las hici\u00e9ramos marcar\u00eda una gran diferencia. Y esa es la mentalidad de mejora continua: siempre buscar oportunidades y estar orientado a soluciones. Reunir a la gente, facilitar, colaborar.<\/p>\n<p>&nbsp;<\/p>\n<p>Esto es, con diferencia, lo m\u00e1s emocionado que he estado en la \u00faltima d\u00e9cada. Ha sido extra\u00f1o si miras la evoluci\u00f3n de los t\u00edtulos, pero siento que este trabajo, s\u00e9 que no ser\u00e1 f\u00e1cil, pero al final del d\u00eda quiero hacer de Hoosier Energy un mejor lugar para trabajar, quiero gente. tener ganas de venir a trabajar. Siempre habr\u00e1 partes de tu trabajo que no te gusten, lo entiendo, pero creo que cuidar a nuestra gente es fundamental para ser una organizaci\u00f3n de alto rendimiento y para lo que somos como cooperativa: Se supone que debemos preocuparnos por las personas, preocuparnos por la comunidad, ayudarnos unos a otros, por lo que estas dos posiciones encarnan esos principios y valores.<\/p>","protected":false},"excerpt":{"rendered":"Tarde o temprano, la vida trae cambios para todos. Para Megan Miller, aceptar el cambio ha sido un estilo de vida durante la mayor parte de dos d\u00e9cadas y no hay signos de ceder."},"author":7,"featured_media":14094,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-14089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spotlight-stories","category-18","description-off"],"acf":false,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Megan Miller Q&amp;A: New role, new experience - Hoosier Energy<\/title>\r\n<meta name=\"description\" content=\"Megan Miller adapts to change with a new role at Hoosier Energy focused on Employee Experience and Continuous Improvement.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.hoosierenergy.com\/es\/news-resources\/megan-miller-qa-new-role-new-experience\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Megan Miller Q&amp;A: New role, new experience - Hoosier Energy\" \/>\r\n<meta property=\"og:description\" content=\"Megan Miller adapts to change with a new role at Hoosier Energy focused on Employee Experience and Continuous Improvement.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.hoosierenergy.com\/es\/news-resources\/megan-miller-qa-new-role-new-experience\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Hoosier Energy\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HoosierEnergy\" \/>\r\n<meta property=\"article:published_time\" content=\"2023-11-14T14:11:08+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-11-14T18:23:20+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/11\/New_MM_CI-Training_1664a.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\r\n\t<meta property=\"og:image:height\" content=\"715\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Jeremy Price\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@hoosierenergy\" \/>\r\n<meta name=\"twitter:site\" content=\"@hoosierenergy\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jeremy Price\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/megan-miller-qa-new-role-new-experience\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/megan-miller-qa-new-role-new-experience\\\/\"},\"author\":{\"name\":\"Jeremy Price\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\"},\"headline\":\"Megan Miller Q&#038;A: New role, new experience\",\"datePublished\":\"2023-11-14T14:11:08+00:00\",\"dateModified\":\"2023-11-14T18:23:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/megan-miller-qa-new-role-new-experience\\\/\"},\"wordCount\":1768,\"image\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/megan-miller-qa-new-role-new-experience\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/New_MM_CI-Training_1664a.jpg\",\"articleSection\":[\"Spotlight Stories\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/megan-miller-qa-new-role-new-experience\\\/\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/megan-miller-qa-new-role-new-experience\\\/\",\"name\":\"Megan Miller Q&A: New role, new experience - Hoosier Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/megan-miller-qa-new-role-new-experience\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/megan-miller-qa-new-role-new-experience\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/New_MM_CI-Training_1664a.jpg\",\"datePublished\":\"2023-11-14T14:11:08+00:00\",\"dateModified\":\"2023-11-14T18:23:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\"},\"description\":\"Megan Miller adapts to change with a new role at Hoosier Energy focused on Employee Experience and Continuous Improvement.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/megan-miller-qa-new-role-new-experience\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/megan-miller-qa-new-role-new-experience\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/megan-miller-qa-new-role-new-experience\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/New_MM_CI-Training_1664a.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/New_MM_CI-Training_1664a.jpg\",\"width\":2400,\"height\":715},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/megan-miller-qa-new-role-new-experience\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hoosierenergy.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Megan Miller Q&#038;A: New role, new experience\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#website\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/\",\"name\":\"Hoosier Energy\",\"description\":\"Powering Community\",\"alternateName\":\"Hoosier Energy Rural Electric Cooperative, Inc.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hoosierenergy.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\",\"name\":\"Jeremy Price\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Megan Miller Q&A: New role, new experience - Hoosier Energy","description":"Megan Miller adapts to change with a new role at Hoosier Energy focused on Employee Experience and Continuous Improvement.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hoosierenergy.com\/es\/news-resources\/megan-miller-qa-new-role-new-experience\/","og_locale":"es_ES","og_type":"article","og_title":"Megan Miller Q&A: New role, new experience - Hoosier Energy","og_description":"Megan Miller adapts to change with a new role at Hoosier Energy focused on Employee Experience and Continuous Improvement.","og_url":"https:\/\/www.hoosierenergy.com\/es\/news-resources\/megan-miller-qa-new-role-new-experience\/","og_site_name":"Hoosier Energy","article_publisher":"https:\/\/www.facebook.com\/HoosierEnergy","article_published_time":"2023-11-14T14:11:08+00:00","article_modified_time":"2023-11-14T18:23:20+00:00","og_image":[{"width":2400,"height":715,"url":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/11\/New_MM_CI-Training_1664a.jpg","type":"image\/jpeg"}],"author":"Jeremy Price","twitter_card":"summary_large_image","twitter_creator":"@hoosierenergy","twitter_site":"@hoosierenergy","twitter_misc":{"Escrito por":"Jeremy Price","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/megan-miller-qa-new-role-new-experience\/#article","isPartOf":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/megan-miller-qa-new-role-new-experience\/"},"author":{"name":"Jeremy Price","@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015"},"headline":"Megan Miller Q&#038;A: New role, new experience","datePublished":"2023-11-14T14:11:08+00:00","dateModified":"2023-11-14T18:23:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/megan-miller-qa-new-role-new-experience\/"},"wordCount":1768,"image":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/megan-miller-qa-new-role-new-experience\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/11\/New_MM_CI-Training_1664a.jpg","articleSection":["Spotlight Stories"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/megan-miller-qa-new-role-new-experience\/","url":"https:\/\/www.hoosierenergy.com\/news-resources\/megan-miller-qa-new-role-new-experience\/","name":"Megan Miller Q&A: New role, new experience - Hoosier Energy","isPartOf":{"@id":"https:\/\/www.hoosierenergy.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/megan-miller-qa-new-role-new-experience\/#primaryimage"},"image":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/megan-miller-qa-new-role-new-experience\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/11\/New_MM_CI-Training_1664a.jpg","datePublished":"2023-11-14T14:11:08+00:00","dateModified":"2023-11-14T18:23:20+00:00","author":{"@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015"},"description":"Megan Miller adapts to change with a new role at Hoosier Energy focused on Employee Experience and Continuous Improvement.","breadcrumb":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/megan-miller-qa-new-role-new-experience\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hoosierenergy.com\/news-resources\/megan-miller-qa-new-role-new-experience\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/megan-miller-qa-new-role-new-experience\/#primaryimage","url":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/11\/New_MM_CI-Training_1664a.jpg","contentUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/11\/New_MM_CI-Training_1664a.jpg","width":2400,"height":715},{"@type":"BreadcrumbList","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/megan-miller-qa-new-role-new-experience\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hoosierenergy.com\/"},{"@type":"ListItem","position":2,"name":"Megan Miller Q&#038;A: New role, new experience"}]},{"@type":"WebSite","@id":"https:\/\/www.hoosierenergy.com\/#website","url":"https:\/\/www.hoosierenergy.com\/","name":"Energ\u00eda de Hoosier","description":"Comunidad de energ\u00eda","alternateName":"Hoosier Energy Rural Electric Cooperative, Inc.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hoosierenergy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015","name":"Jeremy Price"}]}},"date_formatted":"noviembre 14, 2023","category":{"term_id":18,"name":"Spotlight Stories","slug":"spotlight-stories","term_group":0,"term_taxonomy_id":18,"taxonomy":"category","description":"","parent":0,"count":206,"filter":"raw"},"thumbnails":{"default":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/11\/New_MM_CI-Training_1664a.jpg","video":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/11\/New_MM_CI-Training_1664a.jpg"},"gallery":null,"video":null,"_links":{"self":[{"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/posts\/14089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/comments?post=14089"}],"version-history":[{"count":0,"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/posts\/14089\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/media\/14094"}],"wp:attachment":[{"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/media?parent=14089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/categories?post=14089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/es\/wp-json\/wp\/v2\/tags?post=14089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}