{"id":9186,"date":"2023-03-21T11:15:04","date_gmt":"2023-03-21T16:15:04","guid":{"rendered":"https:\/\/www.hoosierenergy.com\/?p=9186"},"modified":"2023-03-21T11:15:04","modified_gmt":"2023-03-21T16:15:04","slug":"der-subcommittee-finding-its-footing","status":"publish","type":"post","link":"https:\/\/www.hoosierenergy.com\/de\/news-resources\/der-subcommittee-finding-its-footing\/","title":{"rendered":"DER-Unterausschuss findet seinen Weg"},"content":{"rendered":"<p>Was vor sechs Monaten als Unbekannt begann, ist zu einem Schl\u00fcsselfaktor f\u00fcr die Zukunft von Hoosier Energy und seinen 18 Mitgliedsgenossenschaften geworden.<\/p>\n<p>&nbsp;<\/p>\n<p>Der Strategieunterausschuss f\u00fcr verteilte Energieressourcen (DER) traf sich im September zum ersten Mal am Hauptsitz von Hoosier Energy in Bloomington und hat seitdem an Dynamik gewonnen.<\/p>\n<p>&nbsp;<\/p>\n<p>Das Komitee, das aus sechs Genossenschaftsvertretern besteht \u2013 Colton Carden von Bartholomew County REMC, Nick Geswein von Harrison REMC, Brian Reynolds von Jackson County REMC, John Gates von Johnson County REMC, Tammy Haenlein von South Central Indiana REMC und Sandy Cason von Whitewater Valley REMC \u2013 wurde auf Ersuchen der Hoosier Energy Managers Association gegr\u00fcndet, um DER-Strategien zu entwickeln, zu bewerten und umzusetzen. Es gibt auch eine Handvoll Hoosier Energy-Komiteemitglieder: Videoproduzent Ben Turner, Mitgliederbeziehungsspezialisten Kyle Coulson und Justin Thompson, Prognoseanalystin Erica Steinfeldt und Regierungsbeziehungsmanager Matt Randall sowie Hoosier Energy-Moderatoren Linda Margison von Emerging Energy Resources und Manager f\u00fcr Mitgliederl\u00f6sungen Blake Kleaving, was insgesamt ein Dutzend ergibt.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201eDass Linda und ich gemeinsam den Unterausschuss unserer Abteilungen f\u00fcr neue Energieressourcen und Mitgliederl\u00f6sungen sponsern, ist ein Beispiel f\u00fcr eine weitere Form integrierter Planungsinitiativen innerhalb von Hoosier zur F\u00f6rderung der Zusammenarbeit und einer verfeinerten strategischen Ausrichtung von Pilotprojekten, Programmen und Bildungsressourcen\u201c, sagte Kleaving.<\/p>\n<p>&nbsp;<\/p>\n<p>Der neue Ausschuss hat seine Wurzeln auch in einer fr\u00fcheren Gruppe \u2013 dem Unterausschuss f\u00fcr Demand Side Management (DSM) \u2013, in dem Cason ebenfalls t\u00e4tig war.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201eNach zwei Jahren im DSM-Komitee bin ich der Meinung, dass gro\u00dfe Fortschritte bei der Verbesserung der Programme und Dienste erzielt wurden, die das HEPN-Marketing und das DSM-Programm ausmachen\u201c, sagte Cason. \u201eDie Gruppe st\u00fctzte ihre Empfehlungen auf interne Programmstatistiken, Daten aus Mitgliederkooperativen-Umfragen und eine anonyme Abstimmung des DSM-Unterausschusses. Nachdem unsere Empfehlungen vorgelegt und von der Managervereinigung genehmigt worden waren, sahen diese Manager die Notwendigkeit, den Unterausschuss DER-Strategie einzurichten.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201eDer Schwerpunkt des neuen Komitees liegt auf den strategischen Priorit\u00e4ten von Hoosier Energy im Bereich verteilter Energieressourcen und integrierter Planung. Die Mitgliedschaft von Mitgliedern aus Hoosiers Abteilung f\u00fcr neue Technologien ist eine gro\u00dfartige Erg\u00e4nzung. Gemeinsam erkunden wir Ideen und Initiativen in Bereichen wie der EV-Strategie und einer Neugestaltung der Rabattprogramme f\u00fcr Privathaushalte und Gewerbe- und Industriekunden.\u201c<\/p>\n<p>&nbsp;<\/p>\n<p>Die Vielfalt der Gruppe \u2013 von Ingenieuren \u00fcber Energieberater bis hin zu Gro\u00dfkunden und mehr \u2013 hat die Arbeit des Unterausschusses unterst\u00fctzt.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201eDiese Mischung aus unterschiedlichen Hintergr\u00fcnden bringt frischen Wind in unsere Diskussionen\u201c, sagte Cason, Director of Member Services, Corporate Relations bei Whitewater Valley. \u201eIch denke, wir k\u00f6nnen zusammenarbeiten und dabei anerkennen, was jeder von uns zur Gruppe beitr\u00e4gt.\u201c<\/p>\n<p>&nbsp;<\/p>\n<p>Haenlein, ebenfalls Unterausschussmitglied und Vizepr\u00e4sident f\u00fcr Mitgliederdienste in South Central Indiana, stimmt dem zu.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201eDie unterschiedlichen Perspektiven geben dem Unterausschuss die M\u00f6glichkeit, Themen aus allen Blickwinkeln zu beleuchten\u201c, sagte sie. \u201eJeder Einzelne bringt in unseren Diskussionen seine Erfahrungen und Erkenntnisse ein.\u201c<\/p>\n<p>&nbsp;<\/p>\n<p>Im Mittelpunkt dieser Diskussionen steht nicht nur die Zukunft der Branche, sondern auch die der Genossenschaftsmitglieder, die die angebotenen Programme weiterhin als wertvoll und zufriedenstellend empfinden. Diese Bem\u00fchungen decken das gesamte Spektrum ab.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201eBildungsressourcen sind ein gemeinsames Thema in der Gruppe\u201c, sagte Cason. \u201eEs besteht auch ein Gruppenkonsens, dass unsere Entscheidungen und\/oder Empfehlungen von den Mitgliedern getragen werden sollten.\u201c<\/p>\n<p>&nbsp;<\/p>\n<p>Haenlein sagte: \u201eDer Schwerpunkt des Unterausschusses auf neue Technologien war eine Priorit\u00e4t. Wir diskutieren bei jedem Treffen Forschungsergebnisse und Daten zu neuen Technologien, um zuk\u00fcnftige Programme, die Mitgliedern und Genossenschaften zugute kommen, optimal zu positionieren.\u201c<\/p>\n<p>&nbsp;<\/p>\n<p>Die Forschung und Datenerfassung, von Elektrofahrzeugen bis hin zu intelligenten Thermostaten und vielem mehr, steht f\u00fcr den DER-Unterausschuss, der nach sechs Monaten seiner zweij\u00e4hrigen Amtszeit begonnen hat, Fu\u00df zu fassen, weiterhin im Vordergrund. Davon werden die kommenden Ma\u00dfnahmen abh\u00e4ngen.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201eUnser aktueller Handlungsschwerpunkt liegt auf der Festlegung der Priorit\u00e4ten f\u00fcr den Unterausschuss und der Bewertung k\u00fcnftiger Programme\u201c, sagte Haenlein. \u201eWenn wir weiter an Dynamik gewinnen, k\u00f6nnen wir uns eingehender mit spezifischen Programmpriorit\u00e4ten wie Bildungsinstrumenten, Erschwinglichkeit und Zuverl\u00e4ssigkeit befassen.\u201c<\/p>","protected":false},"excerpt":{"rendered":"Was vor sechs Monaten noch als Unbekannter begann, ist zu einem Schl\u00fcsselfaktor f\u00fcr die Zukunft von Hoosier Energy und seinen 18 Mitgliedskooperativen geworden. Die DER (Distributed Energy"},"author":7,"featured_media":9187,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-9186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spotlight-stories","category-18","description-off"],"acf":false,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>DER Subcommittee finding its footing - Hoosier Energy<\/title>\r\n<meta name=\"description\" content=\"Hoosier Energy&#039;s Distributed Energy Resources Subcommittee is new but finding its footing with an eye on the future.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.hoosierenergy.com\/de\/news-resources\/der-subcommittee-finding-its-footing\/\" \/>\r\n<meta property=\"og:locale\" content=\"de_DE\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"DER Subcommittee finding its footing - Hoosier Energy\" \/>\r\n<meta property=\"og:description\" content=\"Hoosier Energy&#039;s Distributed Energy Resources Subcommittee is new but finding its footing with an eye on the future.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.hoosierenergy.com\/de\/news-resources\/der-subcommittee-finding-its-footing\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Hoosier Energy\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HoosierEnergy\" \/>\r\n<meta property=\"article:published_time\" content=\"2023-03-21T16:15:04+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/03\/possessed-photography-znCLdh5-Srk-unsplash.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"4787\" \/>\r\n\t<meta property=\"og:image:height\" content=\"3509\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Jeremy Price\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@hoosierenergy\" \/>\r\n<meta name=\"twitter:site\" content=\"@hoosierenergy\" \/>\r\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jeremy Price\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/der-subcommittee-finding-its-footing\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/der-subcommittee-finding-its-footing\\\/\"},\"author\":{\"name\":\"Jeremy Price\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\"},\"headline\":\"DER Subcommittee finding its footing\",\"datePublished\":\"2023-03-21T16:15:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/der-subcommittee-finding-its-footing\\\/\"},\"wordCount\":665,\"image\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/der-subcommittee-finding-its-footing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/possessed-photography-znCLdh5-Srk-unsplash.jpg\",\"articleSection\":[\"Spotlight Stories\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/der-subcommittee-finding-its-footing\\\/\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/der-subcommittee-finding-its-footing\\\/\",\"name\":\"DER Subcommittee finding its footing - Hoosier Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/der-subcommittee-finding-its-footing\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/der-subcommittee-finding-its-footing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/possessed-photography-znCLdh5-Srk-unsplash.jpg\",\"datePublished\":\"2023-03-21T16:15:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\"},\"description\":\"Hoosier Energy's Distributed Energy Resources Subcommittee is new but finding its footing with an eye on the future.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/der-subcommittee-finding-its-footing\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/der-subcommittee-finding-its-footing\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/der-subcommittee-finding-its-footing\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/possessed-photography-znCLdh5-Srk-unsplash.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/possessed-photography-znCLdh5-Srk-unsplash.jpg\",\"width\":4787,\"height\":3509},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/der-subcommittee-finding-its-footing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hoosierenergy.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DER Subcommittee finding its footing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#website\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/\",\"name\":\"Hoosier Energy\",\"description\":\"Powering Community\",\"alternateName\":\"Hoosier Energy Rural Electric Cooperative, Inc.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hoosierenergy.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\",\"name\":\"Jeremy Price\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DER Subcommittee finding its footing - Hoosier Energy","description":"Hoosier Energy's Distributed Energy Resources Subcommittee is new but finding its footing with an eye on the future.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hoosierenergy.com\/de\/news-resources\/der-subcommittee-finding-its-footing\/","og_locale":"de_DE","og_type":"article","og_title":"DER Subcommittee finding its footing - Hoosier Energy","og_description":"Hoosier Energy's Distributed Energy Resources Subcommittee is new but finding its footing with an eye on the future.","og_url":"https:\/\/www.hoosierenergy.com\/de\/news-resources\/der-subcommittee-finding-its-footing\/","og_site_name":"Hoosier Energy","article_publisher":"https:\/\/www.facebook.com\/HoosierEnergy","article_published_time":"2023-03-21T16:15:04+00:00","og_image":[{"width":4787,"height":3509,"url":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/03\/possessed-photography-znCLdh5-Srk-unsplash.jpg","type":"image\/jpeg"}],"author":"Jeremy Price","twitter_card":"summary_large_image","twitter_creator":"@hoosierenergy","twitter_site":"@hoosierenergy","twitter_misc":{"Verfasst von":"Jeremy Price","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/der-subcommittee-finding-its-footing\/#article","isPartOf":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/der-subcommittee-finding-its-footing\/"},"author":{"name":"Jeremy Price","@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015"},"headline":"DER Subcommittee finding its footing","datePublished":"2023-03-21T16:15:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/der-subcommittee-finding-its-footing\/"},"wordCount":665,"image":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/der-subcommittee-finding-its-footing\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/03\/possessed-photography-znCLdh5-Srk-unsplash.jpg","articleSection":["Spotlight Stories"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/der-subcommittee-finding-its-footing\/","url":"https:\/\/www.hoosierenergy.com\/news-resources\/der-subcommittee-finding-its-footing\/","name":"DER Subcommittee finding its footing - Hoosier Energy","isPartOf":{"@id":"https:\/\/www.hoosierenergy.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/der-subcommittee-finding-its-footing\/#primaryimage"},"image":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/der-subcommittee-finding-its-footing\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/03\/possessed-photography-znCLdh5-Srk-unsplash.jpg","datePublished":"2023-03-21T16:15:04+00:00","author":{"@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015"},"description":"Hoosier Energy's Distributed Energy Resources Subcommittee is new but finding its footing with an eye on the future.","breadcrumb":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/der-subcommittee-finding-its-footing\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hoosierenergy.com\/news-resources\/der-subcommittee-finding-its-footing\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/der-subcommittee-finding-its-footing\/#primaryimage","url":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/03\/possessed-photography-znCLdh5-Srk-unsplash.jpg","contentUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/03\/possessed-photography-znCLdh5-Srk-unsplash.jpg","width":4787,"height":3509},{"@type":"BreadcrumbList","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/der-subcommittee-finding-its-footing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hoosierenergy.com\/"},{"@type":"ListItem","position":2,"name":"DER Subcommittee finding its footing"}]},{"@type":"WebSite","@id":"https:\/\/www.hoosierenergy.com\/#website","url":"https:\/\/www.hoosierenergy.com\/","name":"Hoosier Energie","description":"Gemeinschaft st\u00e4rken","alternateName":"Hoosier Energy Rural Electric Cooperative, Inc.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hoosierenergy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015","name":"Jeremy Price"}]}},"date_formatted":"M\u00e4rz 21, 2023","category":{"term_id":18,"name":"Spotlight Stories","slug":"spotlight-stories","term_group":0,"term_taxonomy_id":18,"taxonomy":"category","description":"","parent":0,"count":206,"filter":"raw"},"thumbnails":{"default":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/03\/possessed-photography-znCLdh5-Srk-unsplash.jpg","video":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/03\/possessed-photography-znCLdh5-Srk-unsplash.jpg"},"gallery":null,"video":null,"_links":{"self":[{"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/posts\/9186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/comments?post=9186"}],"version-history":[{"count":0,"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/posts\/9186\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/media\/9187"}],"wp:attachment":[{"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/media?parent=9186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/categories?post=9186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/tags?post=9186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}