{"id":7805,"date":"2023-01-31T13:10:40","date_gmt":"2023-01-31T18:10:40","guid":{"rendered":"https:\/\/www.hoosierenergy.com\/?p=7805"},"modified":"2023-01-31T13:48:24","modified_gmt":"2023-01-31T18:48:24","slug":"hoosier-energy-winter-storm-elliott","status":"publish","type":"post","link":"https:\/\/www.hoosierenergy.com\/de\/news-resources\/hoosier-energy-winter-storm-elliott\/","title":{"rendered":"Hoosier Energy muss sich dem Widerstand des Wintersturms Elliott stellen"},"content":{"rendered":"<p>Der Wintersturm Elliott hatte im Dezember heftige Auswirkungen, doch die 18 Mitgliedsgenossenschaften von Hoosier Energy hielten stand und erlebten nur minimale St\u00f6rungen.<\/p>\n<p>&nbsp;<\/p>\n<p>Das System musste einen Rekordschlag verkraften, als die Temperaturen am 22. Dezember innerhalb von 12 Stunden um fast 50 Grad fielen und im gesamten Versorgungsgebiet f\u00fcnf bis sieben Zentimeter Schnee fielen.<\/p>\n<p>&nbsp;<\/p>\n<p>Insgesamt lag die durchschnittliche Systemtemperatur am 22. und 23. Dezember bei minus vier Grad bei starkem Wind. Angesichts einer maximalen anhaltenden Windgeschwindigkeit von 36 Meilen pro Stunde und B\u00f6en von \u00fcber 50 Meilen pro Stunde wurde jeder Aspekt der Stromerzeugung und -\u00fcbertragung \u00fcberwacht.<\/p>\n<p>&nbsp;<\/p>\n<p>Unterwegs erreichte Hoosier Energy einen Allzeit-Systemspitzenwert von 1.828 Megawatt, der gleichzeitig mit dem Spitzenwert der Midwest Independent System Operators (MISO) zusammenfiel. Dieser Spitzenwert, der den bisherigen Rekord von 1.714 MW vom Januar 2019 \u00fcbertraf, wurde in der Stunde erreicht, die am 23. Dezember um 19 Uhr endete.<\/p>\n<p>&nbsp;<\/p>\n<p>MISO gab eine \u201eNotfallwarnung bei maximaler Stromerzeugung\u201c heraus, um die Kraftwerksbetreiber dar\u00fcber zu informieren, dass die Stromversorgung im Netz am 23. Dezember um 17:06 Uhr knapp wurde, sodass alle Anlagen in Bereitschaft sein und bei Bedarf einsatzbereit sein mussten.<\/p>\n<p>&nbsp;<\/p>\n<p>Erdgas floss und war im Holland Energy Plant von Hoosier Energy in Illinois verf\u00fcgbar, wurde aber nicht abgerufen. Das Kraftwerk Worthington musste w\u00e4hrend des Ereignisses am 23. Dezember ebenfalls eingeschaltet werden, w\u00e4hrend andere Kraftwerke in Bereitschaft waren, als Elliott der Versorgungsindustrie eine stehende Acht-Punkte-Z\u00e4hlung erteilte.<\/p>\n<p>&nbsp;<\/p>\n<p>Es gab auch einen Aufruf zu Lastmanagementverfahren bei 16 der 18 am Hoosier Energy Emergency Capacity Portal teilnehmenden Genossenschaften, doch um 21 Uhr desselben Abends wurde die Max-Gen-Warnung aufgehoben.<\/p>\n<p>&nbsp;<\/p>\n<p>Bei den Anlagen von Hoosier Energy gab es keine Zuverl\u00e4ssigkeitsprobleme, nur wenige Unterbrechungen an den Lieferpunkten. Durch kontinuierliche Vorbereitung und Zusammenarbeit sind Hoosier und seine Mitgliedsgenossenschaften gut auf diese und andere Herausforderungen in der Zukunft vorbereitet.<\/p>","protected":false},"excerpt":{"rendered":"Der Wintersturm Elliott hatte im Dezember seine Spuren hinterlassen, aber die 18 Mitgliedsgenossenschaften von Hoosier Energy hielten stand und erlebten nur minimale St\u00f6rungen. Das System verkraftete einen Rekordschlag, als die Temperaturen sanken."},"author":7,"featured_media":7806,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[25,18],"tags":[],"class_list":["post-7805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-spotlight-stories","category-25","category-18","description-off"],"acf":false,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Hoosier Energy sees Winter Storm Elliott put up a fight - Hoosier Energy<\/title>\r\n<meta name=\"description\" content=\"Winter Storm Elliott packed a punch, but Hoosier Energy and its member cooperatives stood tall during the wintry onlsaught.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.hoosierenergy.com\/de\/news-resources\/hoosier-energy-winter-storm-elliott\/\" \/>\r\n<meta property=\"og:locale\" content=\"de_DE\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Hoosier Energy sees Winter Storm Elliott put up a fight - Hoosier Energy\" \/>\r\n<meta property=\"og:description\" content=\"Winter Storm Elliott packed a punch, but Hoosier Energy and its member cooperatives stood tall during the wintry onlsaught.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.hoosierenergy.com\/de\/news-resources\/hoosier-energy-winter-storm-elliott\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Hoosier Energy\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HoosierEnergy\" \/>\r\n<meta property=\"article:published_time\" content=\"2023-01-31T18:10:40+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-01-31T18:48:24+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/01\/New_Snow70_still1.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\r\n\t<meta property=\"og:image:height\" content=\"675\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Jeremy Price\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@hoosierenergy\" \/>\r\n<meta name=\"twitter:site\" content=\"@hoosierenergy\" \/>\r\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jeremy Price\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/hoosier-energy-winter-storm-elliott\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/hoosier-energy-winter-storm-elliott\\\/\"},\"author\":{\"name\":\"Jeremy Price\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\"},\"headline\":\"Hoosier Energy sees Winter Storm Elliott put up a fight\",\"datePublished\":\"2023-01-31T18:10:40+00:00\",\"dateModified\":\"2023-01-31T18:48:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/hoosier-energy-winter-storm-elliott\\\/\"},\"wordCount\":310,\"image\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/hoosier-energy-winter-storm-elliott\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/New_Snow70_still1.jpg\",\"articleSection\":[\"News\",\"Spotlight Stories\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/hoosier-energy-winter-storm-elliott\\\/\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/hoosier-energy-winter-storm-elliott\\\/\",\"name\":\"Hoosier Energy sees Winter Storm Elliott put up a fight - Hoosier Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/hoosier-energy-winter-storm-elliott\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/hoosier-energy-winter-storm-elliott\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/New_Snow70_still1.jpg\",\"datePublished\":\"2023-01-31T18:10:40+00:00\",\"dateModified\":\"2023-01-31T18:48:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\"},\"description\":\"Winter Storm Elliott packed a punch, but Hoosier Energy and its member cooperatives stood tall during the wintry onlsaught.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/hoosier-energy-winter-storm-elliott\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/hoosier-energy-winter-storm-elliott\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/hoosier-energy-winter-storm-elliott\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/New_Snow70_still1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/New_Snow70_still1.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/hoosier-energy-winter-storm-elliott\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hoosierenergy.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hoosier Energy sees Winter Storm Elliott put up a fight\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#website\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/\",\"name\":\"Hoosier Energy\",\"description\":\"Powering Community\",\"alternateName\":\"Hoosier Energy Rural Electric Cooperative, Inc.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hoosierenergy.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\",\"name\":\"Jeremy Price\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hoosier Energy sieht Wintersturm Elliott Widerstand leisten - Hoosier Energy","description":"Der Wintersturm Elliott hatte es in sich, aber Hoosier Energy und ihre Mitgliedsgenossenschaften hielten dem winterlichen Ansturm stand.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hoosierenergy.com\/de\/news-resources\/hoosier-energy-winter-storm-elliott\/","og_locale":"de_DE","og_type":"article","og_title":"Hoosier Energy sees Winter Storm Elliott put up a fight - Hoosier Energy","og_description":"Winter Storm Elliott packed a punch, but Hoosier Energy and its member cooperatives stood tall during the wintry onlsaught.","og_url":"https:\/\/www.hoosierenergy.com\/de\/news-resources\/hoosier-energy-winter-storm-elliott\/","og_site_name":"Hoosier Energy","article_publisher":"https:\/\/www.facebook.com\/HoosierEnergy","article_published_time":"2023-01-31T18:10:40+00:00","article_modified_time":"2023-01-31T18:48:24+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/01\/New_Snow70_still1.jpg","type":"image\/jpeg"}],"author":"Jeremy Price","twitter_card":"summary_large_image","twitter_creator":"@hoosierenergy","twitter_site":"@hoosierenergy","twitter_misc":{"Verfasst von":"Jeremy Price","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/hoosier-energy-winter-storm-elliott\/#article","isPartOf":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/hoosier-energy-winter-storm-elliott\/"},"author":{"name":"Jeremy Price","@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015"},"headline":"Hoosier Energy sees Winter Storm Elliott put up a fight","datePublished":"2023-01-31T18:10:40+00:00","dateModified":"2023-01-31T18:48:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/hoosier-energy-winter-storm-elliott\/"},"wordCount":310,"image":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/hoosier-energy-winter-storm-elliott\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/01\/New_Snow70_still1.jpg","articleSection":["News","Spotlight Stories"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/hoosier-energy-winter-storm-elliott\/","url":"https:\/\/www.hoosierenergy.com\/news-resources\/hoosier-energy-winter-storm-elliott\/","name":"Hoosier Energy sieht Wintersturm Elliott Widerstand leisten - Hoosier Energy","isPartOf":{"@id":"https:\/\/www.hoosierenergy.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/hoosier-energy-winter-storm-elliott\/#primaryimage"},"image":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/hoosier-energy-winter-storm-elliott\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/01\/New_Snow70_still1.jpg","datePublished":"2023-01-31T18:10:40+00:00","dateModified":"2023-01-31T18:48:24+00:00","author":{"@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015"},"description":"Der Wintersturm Elliott hatte es in sich, aber Hoosier Energy und ihre Mitgliedsgenossenschaften hielten dem winterlichen Ansturm stand.","breadcrumb":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/hoosier-energy-winter-storm-elliott\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hoosierenergy.com\/news-resources\/hoosier-energy-winter-storm-elliott\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/hoosier-energy-winter-storm-elliott\/#primaryimage","url":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/01\/New_Snow70_still1.jpg","contentUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/01\/New_Snow70_still1.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/hoosier-energy-winter-storm-elliott\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hoosierenergy.com\/"},{"@type":"ListItem","position":2,"name":"Hoosier Energy sees Winter Storm Elliott put up a fight"}]},{"@type":"WebSite","@id":"https:\/\/www.hoosierenergy.com\/#website","url":"https:\/\/www.hoosierenergy.com\/","name":"Hoosier Energie","description":"Gemeinschaft st\u00e4rken","alternateName":"Hoosier Energy Rural Electric Cooperative, Inc.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hoosierenergy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015","name":"Jeremy Price"}]}},"date_formatted":"Januar 31, 2023","category":{"term_id":25,"name":"News","slug":"news","term_group":0,"term_taxonomy_id":25,"taxonomy":"category","description":"","parent":0,"count":27,"filter":"raw"},"thumbnails":{"default":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/01\/New_Snow70_still1.jpg","video":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2023\/01\/New_Snow70_still1.jpg"},"gallery":null,"video":null,"_links":{"self":[{"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/posts\/7805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/comments?post=7805"}],"version-history":[{"count":0,"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/posts\/7805\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/media\/7806"}],"wp:attachment":[{"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/media?parent=7805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/categories?post=7805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/tags?post=7805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}