{"id":17170,"date":"2024-09-11T16:25:38","date_gmt":"2024-09-11T21:25:38","guid":{"rendered":"https:\/\/www.hoosierenergy.com\/?p=17170"},"modified":"2024-09-11T16:25:38","modified_gmt":"2024-09-11T21:25:38","slug":"ashley-bowling-qa-on-her-own-unique-journey","status":"publish","type":"post","link":"https:\/\/www.hoosierenergy.com\/de\/news-resources\/ashley-bowling-qa-on-her-own-unique-journey\/","title":{"rendered":"Ashley Bowling Q&amp;A: \u00dcber ihre eigene, einzigartige Reise"},"content":{"rendered":"<p>Was als ihr erster \u201eJob f\u00fcr gro\u00dfe M\u00e4dchen\u201c begann, hat sich f\u00fcr Ashley Bowling zu einer Karriere entwickelt.<\/p>\n<p>&nbsp;<\/p>\n<p>Nach nunmehr anderthalb Jahren als Executive Assistant bei Hoosier Energy ist Bowling mehr als die neue Melanie. Sie ist ihre eigene Ashley und hat sich k\u00fcrzlich mit GridLines zusammengesetzt, um dar\u00fcber und \u00fcber vieles mehr zu sprechen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>F: Wie sind Sie bei Hoosier angefangen?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>A:<\/strong> Auf die Idee, mich auf eine Stelle in der Verwaltung zu bewerben, kam ich von Pam Raisor. Ich bin mit ihren Kindern aufgewachsen, die auf dieselbe High School gingen, meine Mutter und sie waren schon immer befreundet, und sie schlug mir vor, mich auf die befristete Stelle bei Hoosier zu bewerben. Ich sagte: \u201eDas w\u00fcrde mir gefallen. Ich h\u00e4tte gern etwas Festeres.\u201c<\/p>\n<p>&nbsp;<\/p>\n<p>Ich war 19 Jahre alt und hatte gerade einen Sommer und ein Semester an der Indiana University hinter mir. Ich wusste, dass ich irgendwann wieder nach Bloomington (von Brown County) ziehen wollte. Ich bewarb mich, bekam im Auto den Anruf und war so aufgeregt.<\/p>\n<p>&nbsp;<\/p>\n<p>Das war mein erster Job als erwachsene Frau. Am ersten Tag rief ich meine Mutter an und sagte ihr: \u201eDas wirst du nie glauben. Ich habe meinen eigenen Computer, meine eigene Arbeitskabine, alle meine eigenen Arbeitsmaterialien.\u201c Ich dachte, ich w\u00e4re der Gr\u00f6\u00dfte, es war so cool.<\/p>\n<p>&nbsp;<\/p>\n<p>Ich habe etwa drei Jahre lang als Aushilfe gearbeitet, und als eine Stelle im Verwaltungsdienst frei wurde, habe ich mich darauf beworben und unter Kathy Kardynalski gearbeitet. Ich habe von etwa 2010 bis 2015 mit ihr zusammengearbeitet.<\/p>\n<p>&nbsp;<\/p>\n<p>Im Laufe der Jahre bin ich eingesprungen, wenn die Buchhaltung Hilfe bei einem Prozess brauchte, und habe bei Bedarf viele Sekretariatsarbeiten \u00fcbernommen. Ich habe einfach mal einen Vorgeschmack darauf bekommen, wie es ist, diese verschiedenen Positionen auszuf\u00fcllen, und das hat in mir den Wunsch geweckt, dass ich das eines Tages auch machen m\u00f6chte. Ich wusste, dass es mir helfen w\u00fcrde, diese Positionen zu \u00fcbernehmen und jede Chance zu ergreifen, die sich mir bietet.<\/p>\n<p>&nbsp;<\/p>\n<p>Ich begann 2015 bei Rob Horton zu arbeiten. Rob stellte mich als Sekret\u00e4rin f\u00fcr die Betriebsabteilung ein und ich war acht Jahre lang unter Rob. In dieser Rolle konnte ich viel mehr dar\u00fcber lernen, was hinter den Kulissen aller Werke passiert und wie Hoosier funktioniert \u2013 im wahrsten Sinne des Wortes!<\/p>\n<p>&nbsp;<\/p>\n<p>Als ich die Stelle als Executive Assistant antrat, war der Wechsel vom operativen Gesch\u00e4ft zur Arbeit mit dem Vorstand eine gro\u00dfe Umstellung. Aber das schien eine nat\u00fcrliche Entwicklung zu sein, also machte es einfach Sinn.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>F: Sind Sie nerv\u00f6s, eine gr\u00f6\u00dfere Rolle zu \u00fcbernehmen?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>A:<\/strong> Da gab es viele. Ich hatte noch nie im Sitzungssaal gesessen und mit vielen der Direktoren gesprochen, also wusste ich einfach nicht, was in dieser Rolle vor sich geht und was alles dazugeh\u00f6rt \u2013 aber ich bin ein ziemlich kontaktfreudiger Mensch, also wurde es viel einfacher, als ich erst einmal da war und alle kennengelernt hatte. Viele der Prozesse, denen ich jetzt folge, folgen demselben Muster. Insgesamt war es ein wirklich einfacher \u00dcbergang. Die Zusammenarbeit mit Donna, ihren Mitarbeitern und allen Direktoren und CEOs war wunderbar.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_17172\" style=\"width: 290px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-17172\" class=\"wp-image-17172\" src=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/09\/Bowling_Family-200x300.jpg\" alt=\"\" width=\"280\" height=\"420\" srcset=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/09\/Bowling_Family-200x300.jpg 200w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/09\/Bowling_Family-683x1024.jpg 683w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/09\/Bowling_Family-768x1152.jpg 768w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/09\/Bowling_Family-1024x1536.jpg 1024w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/09\/Bowling_Family-1365x2048.jpg 1365w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/09\/Bowling_Family-8x12.jpg 8w, https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2024\/09\/Bowling_Family-scaled.jpg 1707w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" \/><p id=\"caption-attachment-17172\" class=\"wp-caption-text\">Die Bowling-Familie.<\/p><\/div>\n<p><strong>F: F\u00fcr diejenigen, die es noch nicht wissen: Erz\u00e4hlen Sie uns, was Sie als Assistentin der Gesch\u00e4ftsleitung machen.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>A:<\/strong> Kurz gesagt bin ich die wichtigste Verbindung zwischen Hoosier Energy und unserem Vorstand. Wann immer sie etwas brauchen oder Fragen haben, bin ich da, um zu helfen. Ich bereite Gutscheine f\u00fcr die Zeit vor, die sie bei Sitzungen verbringen. Ich richte auch die Call-to-Order-Sites ein und bereite alles f\u00fcr jede Vorstands- oder Ausschusssitzung vor. Der Vorstand nutzt seine iPads, um auf alle notwendigen Sitzungsinformationen zuzugreifen.<\/p>\n<p>Ich plane auch Meetings und unterst\u00fctze viele andere Teams hier bei Hoosier. Die Meetings der F\u00fchrungsebene, die REMC-Meetings, und ich helfe auch Scott Bowers bei der Managers Association, also mache ich wirklich von allem ein bisschen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>F: Was macht Ihnen an Ihrem Job Spa\u00df?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Was mir am meisten Spa\u00df macht, ist, dass es jeden Tag etwas Neues gibt. Ich komme nicht hierher und mache einfach das Gleiche. Es gibt zwar \u00e4hnliche Dinge, aber von Tag zu Tag gibt es immer etwas Neues. An manchen Tagen habe ich das Gef\u00fchl, in 20 verschiedene Richtungen gezogen zu werden, aber ich ern\u00e4hre mich von der Gesch\u00e4ftigkeit, weil ich drei Kleine unter 10 Jahren zu Hause habe. Das Chaos hier bei der Arbeit geht weiter, aber es ist gutes Chaos, kein schlechtes Chaos.<\/p>\n<p>&nbsp;<\/p>\n<p>Ich liebe es auch, mit allen bei den Vorstandssitzungen und im B\u00fcro zu sprechen. Ich liebe es, mit allen zu interagieren und nicht nur \u00fcber das Gesch\u00e4ftliche zu reden, sondern auch eine Verbindung zu haben, um \u00fcber das zu sprechen, was in ihrem Privatleben vor sich geht.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>F: Gab es in den ersten anderthalb Jahren irgendwelche bedeutenden \u00c4nderungen?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>A:<\/strong> Die Menge an Papier, die wir fr\u00fcher verbraucht haben. Ich bin ein gro\u00dfer Fan der elektronischen Ablage oder des E-Mail-Versands. Ich arbeite zwar immer noch mit Papier, aber elektronisch ist der richtige Weg.<\/p>\n<p>&nbsp;<\/p>\n<p>Wenn ein Dokument in die zentrale Ablage wandert, liegen nicht mehr drei, vier oder f\u00fcnf Kopien im B\u00fcro herum. Wir haben viel geschreddert und Dinge aussortiert, die wir nicht mehr brauchten, also war es eine Art Abwechslung, als ich diese Rolle \u00fcbernahm.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201eCall to Order\u201c hat uns so viel Papier gespart!<\/p>\n<p>&nbsp;<\/p>\n<p><strong>F: Bevor wir zum Schluss kommen, erz\u00e4hlen Sie uns etwas \u00fcber Ihr Privatleben?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>A:<\/strong> Mein Mann hei\u00dft Chad. Er besitzt hier in Bloomington sein eigenes Maurerunternehmen namens Elite Masonry und beginnt auch mit Hausrenovierungen. Er hat 2016 die Maurergewerkschaft verlassen, um sich selbstst\u00e4ndig zu machen. Vor Kurzem hat er auch mit dem Airbnb-Gesch\u00e4ft begonnen.<\/p>\n<p>&nbsp;<\/p>\n<p>Wir haben drei Kinder. Der \u00e4lteste ist Tristan, 9, meine mittlere Tochter Addie ist 6 und meine j\u00fcngste Tochter ist Brylee, sie wird diesen Monat 4. Wir leben auf der Ostseite von Bloomington und haben dort vor fast drei Jahren ein Haus gebaut. Wir haben gerade mit Tristan angefangen, auf Reisen Baseball zu spielen \u2013 wir sind gespannt, wie das aussieht. Er ist besessen von Baseball.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>F: Was ist mit Hobbys\/Interessen?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>A:<\/strong> Ich bin ein gro\u00dfer Kaffeefan und gehe deshalb gerne in verschiedene Caf\u00e9s. Ich probiere wirklich alles aus, was auf der Karte steht. In meiner Gegend sind Soma und Inkwell meine Favoriten. Und ich reise gern in verschiedene St\u00e4dte. Wir waren diesen Sommer gerade in Chicago und haben letztes Jahr einen Ausflug zum Zion-Nationalpark und zum Grand Canyon gemacht. Mein Mann und ich gehen gerne zu Country-Konzerten. Unser Jubil\u00e4umsausflug findet jedes Jahr im Juni zum CMA Fest statt.<\/p>","protected":false},"excerpt":{"rendered":"Was als ihr erster \u201eJob f\u00fcr gro\u00dfe M\u00e4dchen\u201c begann, ist f\u00fcr Ashley Bowling zu einer Karriere geworden. Seit nunmehr anderthalb Jahren ist sie als Executive Assistant bei Hoosier Energy t\u00e4tig."},"author":7,"featured_media":7371,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[50,18],"tags":[],"class_list":["post-17170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-qa","category-spotlight-stories","category-50","category-18","description-off"],"acf":false,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Ashley Bowling Q&amp;A: On her own unique journey - Hoosier Energy<\/title>\r\n<meta name=\"description\" content=\"Now Hoosier Energy&#039;s Executive Assistant, Ashley Bowling has followed her own path after starting as a temp.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.hoosierenergy.com\/de\/news-resources\/ashley-bowling-qa-on-her-own-unique-journey\/\" \/>\r\n<meta property=\"og:locale\" content=\"de_DE\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Ashley Bowling Q&amp;A: On her own unique journey - Hoosier Energy\" \/>\r\n<meta property=\"og:description\" content=\"Now Hoosier Energy&#039;s Executive Assistant, Ashley Bowling has followed her own path after starting as a temp.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.hoosierenergy.com\/de\/news-resources\/ashley-bowling-qa-on-her-own-unique-journey\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Hoosier Energy\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HoosierEnergy\" \/>\r\n<meta property=\"article:published_time\" content=\"2024-09-11T21:25:38+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2021\/12\/Sunrise-transmission-line.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Jeremy Price\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@hoosierenergy\" \/>\r\n<meta name=\"twitter:site\" content=\"@hoosierenergy\" \/>\r\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jeremy Price\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/ashley-bowling-qa-on-her-own-unique-journey\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/ashley-bowling-qa-on-her-own-unique-journey\\\/\"},\"author\":{\"name\":\"Jeremy Price\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\"},\"headline\":\"Ashley Bowling Q&#038;A: On her own unique journey\",\"datePublished\":\"2024-09-11T21:25:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/ashley-bowling-qa-on-her-own-unique-journey\\\/\"},\"wordCount\":1124,\"image\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/ashley-bowling-qa-on-her-own-unique-journey\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Sunrise-transmission-line.jpg\",\"articleSection\":[\"Q&amp;A\",\"Spotlight Stories\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/ashley-bowling-qa-on-her-own-unique-journey\\\/\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/ashley-bowling-qa-on-her-own-unique-journey\\\/\",\"name\":\"Ashley Bowling Q&A: On her own unique journey - Hoosier Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/ashley-bowling-qa-on-her-own-unique-journey\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/ashley-bowling-qa-on-her-own-unique-journey\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Sunrise-transmission-line.jpg\",\"datePublished\":\"2024-09-11T21:25:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\"},\"description\":\"Now Hoosier Energy's Executive Assistant, Ashley Bowling has followed her own path after starting as a temp.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/ashley-bowling-qa-on-her-own-unique-journey\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/ashley-bowling-qa-on-her-own-unique-journey\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/ashley-bowling-qa-on-her-own-unique-journey\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Sunrise-transmission-line.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hoosierenergy.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Sunrise-transmission-line.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/news-resources\\\/ashley-bowling-qa-on-her-own-unique-journey\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hoosierenergy.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ashley Bowling Q&#038;A: On her own unique journey\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#website\",\"url\":\"https:\\\/\\\/www.hoosierenergy.com\\\/\",\"name\":\"Hoosier Energy\",\"description\":\"Powering Community\",\"alternateName\":\"Hoosier Energy Rural Electric Cooperative, Inc.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hoosierenergy.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hoosierenergy.com\\\/#\\\/schema\\\/person\\\/13b6f80b0626754a8c450d50a63d4015\",\"name\":\"Jeremy Price\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ashley Bowling im Interview: \u00dcber ihren ganz eigenen Weg \u2013 Hoosier Energy","description":"Ashley Bowling, die heute als Executive Assistant bei Hoosier Energy arbeitet, hat nach ihrer T\u00e4tigkeit als Aushilfe ihren eigenen Weg eingeschlagen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hoosierenergy.com\/de\/news-resources\/ashley-bowling-qa-on-her-own-unique-journey\/","og_locale":"de_DE","og_type":"article","og_title":"Ashley Bowling Q&A: On her own unique journey - Hoosier Energy","og_description":"Now Hoosier Energy's Executive Assistant, Ashley Bowling has followed her own path after starting as a temp.","og_url":"https:\/\/www.hoosierenergy.com\/de\/news-resources\/ashley-bowling-qa-on-her-own-unique-journey\/","og_site_name":"Hoosier Energy","article_publisher":"https:\/\/www.facebook.com\/HoosierEnergy","article_published_time":"2024-09-11T21:25:38+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2021\/12\/Sunrise-transmission-line.jpg","type":"image\/jpeg"}],"author":"Jeremy Price","twitter_card":"summary_large_image","twitter_creator":"@hoosierenergy","twitter_site":"@hoosierenergy","twitter_misc":{"Verfasst von":"Jeremy Price","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/ashley-bowling-qa-on-her-own-unique-journey\/#article","isPartOf":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/ashley-bowling-qa-on-her-own-unique-journey\/"},"author":{"name":"Jeremy Price","@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015"},"headline":"Ashley Bowling Q&#038;A: On her own unique journey","datePublished":"2024-09-11T21:25:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/ashley-bowling-qa-on-her-own-unique-journey\/"},"wordCount":1124,"image":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/ashley-bowling-qa-on-her-own-unique-journey\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2021\/12\/Sunrise-transmission-line.jpg","articleSection":["Q&amp;A","Spotlight Stories"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/ashley-bowling-qa-on-her-own-unique-journey\/","url":"https:\/\/www.hoosierenergy.com\/news-resources\/ashley-bowling-qa-on-her-own-unique-journey\/","name":"Ashley Bowling im Interview: \u00dcber ihren ganz eigenen Weg \u2013 Hoosier Energy","isPartOf":{"@id":"https:\/\/www.hoosierenergy.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/ashley-bowling-qa-on-her-own-unique-journey\/#primaryimage"},"image":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/ashley-bowling-qa-on-her-own-unique-journey\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2021\/12\/Sunrise-transmission-line.jpg","datePublished":"2024-09-11T21:25:38+00:00","author":{"@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015"},"description":"Ashley Bowling, die heute als Executive Assistant bei Hoosier Energy arbeitet, hat nach ihrer T\u00e4tigkeit als Aushilfe ihren eigenen Weg eingeschlagen.","breadcrumb":{"@id":"https:\/\/www.hoosierenergy.com\/news-resources\/ashley-bowling-qa-on-her-own-unique-journey\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hoosierenergy.com\/news-resources\/ashley-bowling-qa-on-her-own-unique-journey\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/ashley-bowling-qa-on-her-own-unique-journey\/#primaryimage","url":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2021\/12\/Sunrise-transmission-line.jpg","contentUrl":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2021\/12\/Sunrise-transmission-line.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.hoosierenergy.com\/news-resources\/ashley-bowling-qa-on-her-own-unique-journey\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hoosierenergy.com\/"},{"@type":"ListItem","position":2,"name":"Ashley Bowling Q&#038;A: On her own unique journey"}]},{"@type":"WebSite","@id":"https:\/\/www.hoosierenergy.com\/#website","url":"https:\/\/www.hoosierenergy.com\/","name":"Hoosier Energie","description":"Gemeinschaft st\u00e4rken","alternateName":"Hoosier Energy Rural Electric Cooperative, Inc.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hoosierenergy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.hoosierenergy.com\/#\/schema\/person\/13b6f80b0626754a8c450d50a63d4015","name":"Jeremy Price"}]}},"date_formatted":"September 11, 2024","category":{"term_id":50,"name":"Q&amp;A","slug":"qa","term_group":0,"term_taxonomy_id":50,"taxonomy":"category","description":"","parent":0,"count":5,"filter":"raw"},"thumbnails":{"default":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2021\/12\/Sunrise-transmission-line.jpg","video":"https:\/\/www.hoosierenergy.com\/wp-content\/uploads\/2021\/12\/Sunrise-transmission-line.jpg"},"gallery":null,"video":null,"_links":{"self":[{"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/posts\/17170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/comments?post=17170"}],"version-history":[{"count":0,"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/posts\/17170\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/media\/7371"}],"wp:attachment":[{"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/media?parent=17170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/categories?post=17170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoosierenergy.com\/de\/wp-json\/wp\/v2\/tags?post=17170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}